    {"id":14099,"date":"2025-09-15T22:55:45","date_gmt":"2025-09-16T01:55:45","guid":{"rendered":"https:\/\/gersonguelmann.com.br\/blog\/?p=14099"},"modified":"2025-09-16T14:52:26","modified_gmt":"2025-09-16T17:52:26","slug":"para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender","status":"publish","type":"post","link":"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/","title":{"rendered":"Para Quem Gosta e Entende de Vinho. E Para Quem Bebe, Mesmo Sem Entender"},"content":{"rendered":"<p data-start=\"157\" data-end=\"488\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Recuperei um artigo interessante que reproduzi no meu blog h\u00e1 alguns anos, destinado aos apreciadores de vinhos. Ele serve tanto aos que n\u00e3o passariam vergonha em uma <em data-start=\"324\" data-end=\"345\">degusta\u00e7\u00e3o \u00e0s cegas<\/em> quanto aos que gostam e usufruem da bebida mesmo sem reunir muito conhecimento \u2014 aqueles que nunca se debru\u00e7aram sobre a origem de cada uva.<\/span><\/p>\n<p data-start=\"490\" data-end=\"735\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Antes, cabe um pedido antecipado de desculpas ao meu amigo Alexandre Teixeira, que todas as sextas-feiras nos brinda aqui no <em data-start=\"615\" data-end=\"623\">HojePR<\/em> com sua coluna <em data-start=\"639\" data-end=\"682\">Bons Vinhos, Bons Amigos e Boas Conversas<\/em> \u2014 essa, sim, coisa de profissional para graduados.<\/span><\/p>\n<p data-start=\"737\" data-end=\"1032\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Vale tamb\u00e9m uma curiosidade: n\u00e3o posso me dizer um \u201cabst\u00eamio\u201d, porque a defini\u00e7\u00e3o cl\u00e1ssica n\u00e3o se aplica a mim, assim como a de \u201cabstinente\u201d. Na realidade, nunca tive o h\u00e1bito de beber, o que n\u00e3o me impede de, eventualmente \u2014 e posso dizer \u201cmuito eventualmente\u201d mesmo \u2014 bebericar alguma coisa.<\/span><\/p>\n<p data-start=\"1034\" data-end=\"1322\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Mas, no que se refere aos vinhos, me limito \u2014 e fa\u00e7o com prazer \u2014 a percorrer corredores de supermercados e lojas especializadas para apreciar, veja s\u00f3, os r\u00f3tulos das garrafas. Fa\u00e7o isso com certa regularidade, j\u00e1 que sou o encarregado de adquirir a bebida para a Rosane, minha esposa.<\/span><\/p>\n<p data-start=\"1324\" data-end=\"1426\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Voltando ao artigo a que me referi no in\u00edcio: ele foi publicado h\u00e1 mais de sete anos na <em data-start=\"1412\" data-end=\"1423\">Flipboard<\/em>.<\/span><\/p>\n<p data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.0.0.0\"><span style=\"font-size: 18pt; color: #000000; font-family: tahoma, arial, helvetica, sans-serif;\"><strong>Merlot, Cabernet ou Syrah? Entenda as diferen\u00e7as entre as uvas do vinho<\/strong><\/span><\/p>\n<div class=\"metadata\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.0.0.1\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong><span class=\"author\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.0.0.1.0\">Bruno Garattoni<\/span><span class=\"separator\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.0.0.1.1\">\/<\/span><span class=\"date\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.0.0.1.2\">14 de jun de 2018<\/span><\/strong><\/span><\/div>\n<div data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.0.0.1\">\n<p><span style=\"color: #000000; font-size: 18pt; font-family: tahoma, arial, helvetica, sans-serif;\"><strong>As rainhas das prateleiras<\/strong><\/span><\/p>\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>1. Sauvignon Blanc<br \/>\n<\/strong>Origin\u00e1ria do vale do Loire, a sauvignon blanc produz vinhos frescos, de boa acidez e aroma pronunciado. Esse aroma pode lembrar maracuj\u00e1, piment\u00e3o verde, frutas c\u00edtricas e grama. Os melhores do mundo v\u00eam da regi\u00e3o de Sancerre, no Loire; no Brasil, as melhores compras s\u00e3o os vinhos das \u00e1reas costeiras do Chile, onde a influ\u00eancia do Pac\u00edfico derruba a temperatura (o que \u00e9 bom para essa uva).<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">\u00a0Fran\u00e7a (Loire e Bordeaux), Nova Zel\u00e2ndia, Chile (Leyda e Casablanca).<\/span><\/p>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$5\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>2. Cabernet Sauvignon<\/strong><br \/>\nA cabernet \u00e9, de longe, a uva tinta mais popular que existe. Adaptou-se ao clima de quase todos os pa\u00edses que produzem vinho. Resulta em bebidas de cor escura e muitos taninos, com aromas de cereja, amora, piment\u00e3o verde e hortel\u00e3 \u2212 os exemplares envelhecidos em carvalho remetem a baunilha e chocolate. \u00c9 a uva predominante nos grandes vinhos de M\u00e9doc e Graves, em Bordeaux. Para um vinho bacana e barato, invista num chileno ou num argentino.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:\u00a0<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Fran\u00e7a (Bordeaux), Calif\u00f3rnia, \u00c1frica do Sul, Austr\u00e1lia, It\u00e1lia (Toscana), Espanha (Catalunha), Chile (Maipo).<\/span><\/p>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$11\">\n<p><span style=\"color: #000000; font-size: 18pt; font-family: tahoma, arial, helvetica, sans-serif;\"><strong>3. Chardonnay<\/strong><\/span><br \/>\n<span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Uva branca mais plantada no mundo, a chardonnay \u00e9 usada tanto em espumantes quanto em vinhos tranquilos. Seu perfil arom\u00e1tico \u00e9 bastante vers\u00e1til. A variedade atinge seu auge na Borgonha, onde resulta em vinhos delicados e minerais, com notas de frutas verdes. No Novo Mundo, tendem a ser abaunilhados e amanteigados \u2212 resultado da guarda em barril. Os espumantes nacionais, onde ela geralmente vem misturada \u00e0 pinot noir, s\u00e3o a melhor rela\u00e7\u00e3o custo-benef\u00edcio.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">\u00a0Fran\u00e7a (Borgonha e Champagne), Calif\u00f3rnia, Austr\u00e1lia, Brasil.<\/span><\/p>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$17\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>4. Merlot<br \/>\n<\/strong>\u00c9 a outra uva de Bordeaux, onde faz tabelinha com a cabernet sauvignon. Ela prevalece nos vinhos de denomina\u00e7\u00f5es prestigiadas, como Pomerol. \u00c9 a uva tinta que melhor se adaptou ao sul do Brasil, embora as melhores barganhas do mercado dom\u00e9stico recaiam nos r\u00f3tulos chilenos. Enquanto a cabernet \u00e9 pot\u00eancia, a merlot \u00e9 suavidade \u2212 menos cor e menos taninos em vinhos redondos, suculentos e f\u00e1ceis de beber. No nariz, lembra ameixa e amoras; se envelhecida, adquire cremosidade e notas de baunilha.<br \/>\n<b>Onde d\u00e1:<\/b> Fran\u00e7a (Bordeaux), Chile (Colchagua), Austr\u00e1lia, It\u00e1lia (Toscana), Estados Unidos (Calif\u00f3rnia), Brasil.<\/span><\/p>\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>5. Pinot Noir<br \/>\n<\/strong>H\u00e1 quem diga que a Borgonha, sua regi\u00e3o de origem, \u00e9 o \u00fanico lugar capaz de produzir e trabalhar bem a temperamental pinot noir. N\u00e3o \u00e9 bem assim: os tintos borgonheses s\u00e3o imbat\u00edveis (e car\u00edssimos), mas a pinot tamb\u00e9m consegue bons resultados em outras zonas de clima frio. Produz vinhos de cor vermelha, com aromas de frutas vermelhas e, quando h\u00e1 passagem por carvalho, notas de baunilha e coco. Tamb\u00e9m entra na composi\u00e7\u00e3o de espumantes \u2212 inclusive alguns \u00f3timos brasileiros.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:\u00a0<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Fran\u00e7a (Borgonha e Champagne), Nova Zel\u00e2ndia, Estados Unidos (Oregon), Chile (Leyda e Casablanca), Brasil.<\/span><\/p>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$23\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>6. Malbec<br \/>\n<\/strong>Nativa do sudoeste franc\u00eas, onde se transforma em vinhos r\u00fasticos, encontrou seu lugar ideal na Argentina. O sol abundante do deserto de Mendoza transforma a malbec em vinhos frutados (amora, cereja) e florais (violeta), encorpados e suculentos. Recentemente, o vizinho Chile passou a investir nessa uva, produzindo exemplares de perfil arom\u00e1tico distinto \u2212 com notas mentoladas e de especiarias.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:\u00a0<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Argentina (Mendoza, Salta, Patag\u00f4nia), Fran\u00e7a (Cahors, Bordeaux), Chile (Colchagua).<\/span><\/p>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$29\">\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$35\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>7. Syrah<br \/>\n<\/strong>A syrah \u00e9 a uva tinta que reina no vale do Rh\u00f4ne (sul da Fran\u00e7a), prevalecendo nos blends de vinhos conceituad\u00edssimos, como o C\u00f4te-Rotie e o Hermitage. No nariz, a syrah geralmente lembra especiarias como pimenta negra e um toque levemente defumado. No Novo Mundo, encontrou seu lugar na Austr\u00e1lia, que se tornou refer\u00eancia em vinhos intensos, com aromas de frutas negras e chocolate. L\u00e1, a uva recebe o nome de shiraz.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:\u00a0<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Fran\u00e7a (Rh\u00f4ne e Languedoc), Austr\u00e1lia, \u00c1frica do Sul, EUA (Washington) e Chile (Rapel).<\/span><\/p>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$41\">\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$44\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>8. Riesling<br \/>\n<\/strong>Uva de clima frio, resulta em bebidas minerais e intensamente arom\u00e1ticas. Os exemplares alem\u00e3es podem ser secos ou adocicados.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:\u00a0<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Alemanha, Fran\u00e7a (Als\u00e1cia), Nova Zel\u00e2ndia.<\/span><\/p>\n<\/div>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$46\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>9. Prosecco<br \/>\n<\/strong>Para proteger seus vinhos de imita\u00e7\u00f5es, a It\u00e1lia recentemente mudou o nome desta uva para glera. Produz espumantes que v\u00e3o do sofr\u00edvel ao muito bom.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">\u00a0It\u00e1lia (V\u00eaneto).<\/span><\/p>\n<\/div>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$48\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>10. Nebbiolo<\/strong><br \/>\nA uva-s\u00edmbolo do Piemonte n\u00e3o se adapta bem a outras regi\u00f5es. Sua cor relativamente p\u00e1lida engana: os vinhos s\u00e3o bastante t\u00e2nicos e podem requerer envelhecimento.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:<\/b><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">\u00a0<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">It\u00e1lia (Piemonte).\u00a0<\/span><\/p>\n<\/div>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$50\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>11. Pinotage<br \/>\n<\/strong>Cruzamento de pinot noir e cinsault, fez sucesso somente nos vinhedos sul-africanos. Seus cr\u00edticos dizem que ela produz vinhos com aroma de tinta \u2212 o que n\u00e3o \u00e9 nada bom.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:\u00a0<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">\u00c1frica do Sul.<\/span><\/p>\n<\/div>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$53\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>12. Primitivo<br \/>\n<\/strong>Uva nativa do quente sul da It\u00e1lia, onde gera vinhos tintos suculentos e muito alco\u00f3licos. Nos Estados Unidos, mudou de nome para zinfandel.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">\u00a0It\u00e1lia (Puglia) e EUA (Calif\u00f3rnia).<\/span><\/p>\n<\/div>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$55\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>13. Sangiovese<br \/>\n<\/strong>Variedade t\u00edpica da It\u00e1lia central, resulta em vinhos com acidez marcante \u2212 que podem ser de m\u00e9dio corpo (Chianti) ou encorpados (Brunello de Montalcino).<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:<\/b><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">\u00a0<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">It\u00e1lia (Toscana), EUA (Calif\u00f3rnia).<\/span><\/p>\n<\/div>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$57\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>14. Tannat<br \/>\n<\/strong>Nasceu no pa\u00eds basco franc\u00eas, mas foi adotada pelo Uruguai \u2212 \u00fanico pa\u00eds a investir na tannat como varietal.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">\u00a0Uruguai, EUA (Calif\u00f3rnia).<\/span><\/p>\n<\/div>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$59\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>15. Tempranillo<br \/>\n<\/strong>Uva abundante em toda a Pen\u00ednsula Ib\u00e9rica, resulta em vinhos potentes e ricos em notas de frutas e especiarias. \u00c9 a base dos grandes r\u00f3tulos de Rioja e Ribera del Duero.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1:<\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">\u00a0Espanha (Rioja, Ribera del Duero, Toro, Catalunha), Portugal (Douro, Porto, Alentejo).<\/span><\/p>\n<\/div>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$61\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong>16. Touriga Internacional<br \/>\n<\/strong>Em meio \u00e0 confus\u00e3o das variedades portuguesas, a touriga nacional se destaca \u2212 \u00e9 uma das poucas a serem plantadas isoladamente. O aroma floral (de violeta, principalmente) \u00e9 caracter\u00edstico.<br \/>\n<\/span><b style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Onde d\u00e1: <\/b><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Portugal (Douro, Porto, D\u00e3o).<\/span><\/p>\n<\/div>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$62\">\n<p><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">A mat\u00e9ria no site original <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/flipboard.com\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom.br\"><em><strong>pode ser lida aqui<\/strong><\/em><\/a>.<\/span><\/span><\/p>\n<\/div>\n<div class=\"paragraph\" data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.2.$62\">\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"attachment-266x266 size-266x266 aligncenter\" src=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7.jpg?resize=266%2C266&#038;ssl=1\" sizes=\"(max-width: 266px) 100vw, 266px\" srcset=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg?resize=476%2C476&amp;ssl=1 476w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg?resize=70%2C70&amp;ssl=1 70w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg?resize=127%2C127&amp;ssl=1 127w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg?resize=125%2C125&amp;ssl=1 125w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg?zoom=2&amp;resize=266%2C266&amp;ssl=1 532w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg?zoom=3&amp;resize=266%2C266&amp;ssl=1 798w\" alt=\"\" width=\"266\" height=\"266\" \/><strong><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt;\"><em><a href=\"https:\/\/unsplash.com\/pt-br\/fotografias\/mao-segurando-uvas-escuras-maduras-na-videira-Vi_I-NrDe08\"><span style=\"color: #0000ff;\">Foto: Unsplash<\/span><\/a><\/em><\/span><\/strong><\/p>\n<\/div>\n<\/div>\n<p style=\"text-align: center;\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div data-reactid=\".0.4.$\/@flipboard\/-merlot-cabernet-ou-syrah-entenda-as-dif\/f-7c3bd58efd%2Fcom=1br.0.2.2.0.3.0.0.1\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Recuperei um artigo interessante que reproduzi no meu blog h\u00e1 alguns anos, destinado aos apreciadores de vinhos. Ele serve tanto aos que n\u00e3o passariam vergonha em uma degusta\u00e7\u00e3o \u00e0s cegas quanto aos que gostam e usufruem da bebida mesmo sem reunir muito conhecimento \u2014 aqueles que nunca se debru\u00e7aram sobre a origem de cada uva. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":26338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-14099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Para Quem Gosta e Entende de Vinho. E Para Quem Bebe, Mesmo Sem Entender | Blog do Guelmann<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para Quem Gosta e Entende de Vinho. E Para Quem Bebe, Mesmo Sem Entender | Blog do Guelmann\" \/>\n<meta property=\"og:description\" content=\"Recuperei um artigo interessante que reproduzi no meu blog h\u00e1 alguns anos, destinado aos apreciadores de vinhos. Ele serve tanto aos que n\u00e3o passariam vergonha em uma degusta\u00e7\u00e3o \u00e0s cegas quanto aos que gostam e usufruem da bebida mesmo sem reunir muito conhecimento \u2014 aqueles que nunca se debru\u00e7aram sobre a origem de cada uva. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Guelmann\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T01:55:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T17:52:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gerson Guelmann zs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gerson Guelmann zs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\\\/\"},\"author\":{\"name\":\"Gerson Guelmann zs\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\"},\"headline\":\"Para Quem Gosta e Entende de Vinho. E Para Quem Bebe, Mesmo Sem Entender\",\"datePublished\":\"2025-09-16T01:55:45+00:00\",\"dateModified\":\"2025-09-16T17:52:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\\\/\"},\"wordCount\":1244,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/HojePR-7-scaled.jpg?fit=2560%2C1707&ssl=1\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\\\/\",\"url\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\\\/\",\"name\":\"Para Quem Gosta e Entende de Vinho. E Para Quem Bebe, Mesmo Sem Entender | Blog do Guelmann\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/HojePR-7-scaled.jpg?fit=2560%2C1707&ssl=1\",\"datePublished\":\"2025-09-16T01:55:45+00:00\",\"dateModified\":\"2025-09-16T17:52:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/HojePR-7-scaled.jpg?fit=2560%2C1707&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/HojePR-7-scaled.jpg?fit=2560%2C1707&ssl=1\",\"width\":2560,\"height\":1707},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/\",\"name\":\"Blog do Guelmann\",\"description\":\"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\",\"name\":\"Gerson Guelmann zs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"caption\":\"Gerson Guelmann zs\"},\"description\":\"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.\",\"sameAs\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Para Quem Gosta e Entende de Vinho. E Para Quem Bebe, Mesmo Sem Entender | Blog do Guelmann","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/","og_locale":"pt_BR","og_type":"article","og_title":"Para Quem Gosta e Entende de Vinho. E Para Quem Bebe, Mesmo Sem Entender | Blog do Guelmann","og_description":"Recuperei um artigo interessante que reproduzi no meu blog h\u00e1 alguns anos, destinado aos apreciadores de vinhos. Ele serve tanto aos que n\u00e3o passariam vergonha em uma degusta\u00e7\u00e3o \u00e0s cegas quanto aos que gostam e usufruem da bebida mesmo sem reunir muito conhecimento \u2014 aqueles que nunca se debru\u00e7aram sobre a origem de cada uva. [&hellip;]","og_url":"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/","og_site_name":"Blog do Guelmann","article_published_time":"2025-09-16T01:55:45+00:00","article_modified_time":"2025-09-16T17:52:26+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg","type":"image\/jpeg"}],"author":"Gerson Guelmann zs","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gerson Guelmann zs","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/#article","isPartOf":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/"},"author":{"name":"Gerson Guelmann zs","@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e"},"headline":"Para Quem Gosta e Entende de Vinho. E Para Quem Bebe, Mesmo Sem Entender","datePublished":"2025-09-16T01:55:45+00:00","dateModified":"2025-09-16T17:52:26+00:00","mainEntityOfPage":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/"},"wordCount":1244,"commentCount":0,"image":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg?fit=2560%2C1707&ssl=1","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/","url":"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/","name":"Para Quem Gosta e Entende de Vinho. E Para Quem Bebe, Mesmo Sem Entender | Blog do Guelmann","isPartOf":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/#primaryimage"},"image":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg?fit=2560%2C1707&ssl=1","datePublished":"2025-09-16T01:55:45+00:00","dateModified":"2025-09-16T17:52:26+00:00","author":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gersonguelmann.com.br\/blog\/para-quem-gosta-e-entende-de-vinho-e-para-quem-bebe-mesmo-sem-entender\/#primaryimage","url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg?fit=2560%2C1707&ssl=1","contentUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg?fit=2560%2C1707&ssl=1","width":2560,"height":1707},{"@type":"WebSite","@id":"https:\/\/gersonguelmann.com.br\/blog\/#website","url":"https:\/\/gersonguelmann.com.br\/blog\/","name":"Blog do Guelmann","description":"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gersonguelmann.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e","name":"Gerson Guelmann zs","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","caption":"Gerson Guelmann zs"},"description":"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.","sameAs":["https:\/\/gersonguelmann.com.br\/blog\/"]}]}},"views":74,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/09\/HojePR-7-scaled.jpg?fit=2560%2C1707&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p96e7O-3Fp","jetpack-related-posts":[{"id":16947,"url":"https:\/\/gersonguelmann.com.br\/blog\/mete-o-saca-rolha-uma-variacao-do-carpe-diem\/","url_meta":{"origin":14099,"position":0},"title":"Mete o Saca-Rolha (Uma Varia\u00e7\u00e3o do Carpe Diem)","author":"Gerson Guelmann zs","date":"4 de dezembro de 2023","format":false,"excerpt":"N\u00e3o, muito embora pare\u00e7a, o texto n\u00e3o \u00e9 s\u00f3 para os apreciadores de vinho; \u00e9 uma dessas preciosidades de autoria desconhecida que circulam nas redes.\u00a0 O tema \u00e9 bem apropriado aos dias de hoje, quando a express\u00e3o latina do poeta Hor\u00e1cio se mostra cada vez mais apropriada; \"Carpe Diem\" -\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/12\/HojePR-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/12\/HojePR-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/12\/HojePR-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/12\/HojePR-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/12\/HojePR-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14773,"url":"https:\/\/gersonguelmann.com.br\/blog\/bebedores-de-vinho-gostarao\/","url_meta":{"origin":14099,"position":1},"title":"Bebedores de Vinho Gostar\u00e3o","author":"Gerson Guelmann zs","date":"18 de outubro de 2018","format":false,"excerpt":"Celso Cruz (Brocoi\u00f3), que mant\u00e9m um Blog riqu\u00edssimo em cultura brasileira, publicou uma poesia que dedico aos amigos que apreciam bons vinhos: MATUTO EVOLU\u00cdDO Oxente! Quem foi que disse Que matuto n\u00e3o tem bom gosto Pois eu j\u00e1 acho o oposto Pois vejam o meu vizinho Ele \u00e9 entendido em\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/10\/Uvas-e-Vihos-300x166.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12523,"url":"https:\/\/gersonguelmann.com.br\/blog\/os-sequilhos-de-goiaba-sao-bons-o-problema-e-comigo-mesmo\/","url_meta":{"origin":14099,"position":2},"title":"Os Sequilhos de Goiabada S\u00e3o Bons, o Problema \u00e9 Comigo Mesmo","author":"Gerson Guelmann zs","date":"11 de mar\u00e7o de 2024","format":false,"excerpt":"Jonathan Ara\u00fajo, um Portugu\u00eas acerca de quem n\u00e3o consegui levantar mais informa\u00e7\u00f5es, escreveu nos idos de 2017 uma hist\u00f3ria excelente, que mostra como muitas vezes erramos ao tentar mudar as coisas e especialmente as pessoas, quando n\u00f3s mesmos \u00e9 que precisamos mudar, como ele pr\u00f3prio reconhece. Antes, uma explica\u00e7\u00e3o acerca\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/05\/Sequilhos.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/05\/Sequilhos.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/05\/Sequilhos.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/05\/Sequilhos.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/05\/Sequilhos.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":16997,"url":"https:\/\/gersonguelmann.com.br\/blog\/descascando-tangerinas-ou-pai-comeca-o-comeco-para-quem-tem-saudade-do-pai\/","url_meta":{"origin":14099,"position":3},"title":"Descascando Tangerinas ou &#8220;Pai, Come\u00e7a o Come\u00e7o&#8221; &#8211; Para Quem Tem Saudade do Pai","author":"Gerson Guelmann zs","date":"13 de agosto de 2023","format":false,"excerpt":"O dia de hoje certamente \u00e9 de alegrias para muitos, mas tamb\u00e9m traz saudades e lembran\u00e7as aos que j\u00e1 perderam o Pai. Ent\u00e3o dedico o v\u00eddeo abaixo \u00e0s pessoas que, assim como eu, j\u00e1 n\u00e3o o t\u00eam.\u00a0 Ele traz um texto de autoria desconhecida que \u00e9 ao mesmo tempo singelo\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2019\/06\/tangerine.jpg?fit=960%2C615&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2019\/06\/tangerine.jpg?fit=960%2C615&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2019\/06\/tangerine.jpg?fit=960%2C615&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2019\/06\/tangerine.jpg?fit=960%2C615&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":14855,"url":"https:\/\/gersonguelmann.com.br\/blog\/as-fake-news-e-os-travesseiros-de-penas-2\/","url_meta":{"origin":14099,"position":4},"title":"As Fake News e os Travesseiros de Penas","author":"Gerson Guelmann zs","date":"23 de outubro de 2018","format":false,"excerpt":"O que vou dizer abaixo \u00e9 uma brincadeira, uma express\u00e3o que uso para demonstrar como o assunto me preocupa: - tenho dito aos meus amigos que\u00a0sou contra a pena de morte, exce\u00e7\u00e3o feita aos Espalhadores de Fake News. E os qualifico assim\u00a0mesmo, em mai\u00fascula, porque parece que j\u00e1 constituem em\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/10\/old-church-tower-1.jpg?fit=400%2C500&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5426,"url":"https:\/\/gersonguelmann.com.br\/blog\/reflexoes-sobre-cenas-cotidiano\/","url_meta":{"origin":14099,"position":5},"title":"Reflex\u00f5es Sobre Cenas do Cotidiano","author":"Gerson Guelmann zs","date":"9 de dezembro de 2017","format":false,"excerpt":"Dois bons momentos, hoje, ambos nos caixas de lugares onde estive fazendo compras: 1\u00ba - no supermercado, na fila para pagar, um rapaz simp\u00e1tico me chamou pelo nome.\u00a0Achei-o conhecido, mas, sabe como \u00e9, a mem\u00f3ria aos 70 j\u00e1 n\u00e3o \u00e9 grande coisa... Apresentou-se, ent\u00e3o: foi Maitre em restaurante que costumava\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/12\/Calend%C3%A1rio.jpg?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/12\/Calend%C3%A1rio.jpg?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/12\/Calend%C3%A1rio.jpg?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/12\/Calend%C3%A1rio.jpg?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts\/14099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/comments?post=14099"}],"version-history":[{"count":0,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts\/14099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/media\/26338"}],"wp:attachment":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/media?parent=14099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/categories?post=14099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/tags?post=14099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}