    {"id":26132,"date":"2025-07-11T17:22:30","date_gmt":"2025-07-11T20:22:30","guid":{"rendered":"https:\/\/gersonguelmann.com.br\/blog\/?p=26132"},"modified":"2025-07-17T08:55:49","modified_gmt":"2025-07-17T11:55:49","slug":"uma-casamenteira-nunca-perde-o-fregues","status":"publish","type":"post","link":"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/","title":{"rendered":"Sexta do Humor e da Cultura Judaica &#8211; Uma Casamenteira Nunca Perde o Fregu\u00eas"},"content":{"rendered":"<p data-start=\"150\" data-end=\"186\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\"><em><strong data-start=\"150\" data-end=\"186\">Uma Casamenteira Nunca Perde o Fregu\u00eas<br \/>\n<\/strong><\/em>Durante o servi\u00e7o na sinagoga que frequentava, Dona Leah, uma casamenteira &#8216;das antigas&#8217; n\u00e3o conseguiu deixar de notar um jovem simp\u00e1tico entrando no templo. Ela nunca o tinha visto antes, ent\u00e3o, ao final do servi\u00e7o, foi at\u00e9 ele e se apresentou.<\/span><br data-start=\"319\" data-end=\"322\" \/><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\">\u2014 Ol\u00e1, eu sou Leah Gold \u2014 disse. \u2014 Meu marido e eu somos membros desta sinagoga h\u00e1 muitos anos.<\/span><br data-start=\"419\" data-end=\"422\" \/><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\">\u2014 Ol\u00e1 para voc\u00ea tamb\u00e9m \u2014 ele respondeu. \u2014 Meu nome \u00e9 Mervyn.<\/span><br data-start=\"481\" data-end=\"484\" \/><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\">\u2014 Nunca te vi por aqui \u2014 disse Leah. \u2014 \u00c9 sua primeira vez aqui?<\/span><br data-start=\"545\" data-end=\"548\" \/><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\">\u2014 Sim, \u00e9 sim \u2014 respondeu Mervyn. \u2014 Acabei de me mudar para c\u00e1.<\/span><br data-start=\"617\" data-end=\"620\" \/><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\">\u2014 Voc\u00ea fez uma \u00f3tima escolha, Mervyn \u2014 diz Leah. \u2014 A cidade \u00e9 muito acolhedora e aqui na nossa sinagoga somos conhecidos por sermos ainda mais calorosos. E onde est\u00e1 o resto da sua fam\u00edlia?<\/span><br data-start=\"706\" data-end=\"709\" \/><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\">\u2014 Eles ainda moram no norte do pa\u00eds \u2014 respondeu Mervyn. \u2014 Eu vim sozinho para c\u00e1. Sou solteiro.<br \/>\n<\/span><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\">Ao ouvir a palavra \u201csolteiro\u201d, os ouvidos de Leah se animaram e ela j\u00e1 antecipou uma nova conquista.<\/span><br data-start=\"871\" data-end=\"874\" \/><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\">\u2014 Que bom, Mervyn \u2014 ela disse. \u2014 Voc\u00ea <em data-start=\"910\" data-end=\"919\">precisa<\/em> conhecer Naomi, a filha dos Blum. Ela tamb\u00e9m \u00e9 solteira e&#8230;<br \/>\n<\/span><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\">Mervyn a interrompeu e disse:<\/span><br data-start=\"1004\" data-end=\"1007\" \/><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\">\u2014 Seria perda de tempo, Sra. Gold. Sinto muito em lhe desapontar, mas eu sou gay.<br \/>\n<\/span><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\">Sem perder um segundo, Leah respondeu:<\/span><br data-start=\"1122\" data-end=\"1125\" \/><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt; color: #000000;\">\u2014 Sem problema. Nesse caso, voc\u00ea <em data-start=\"1158\" data-end=\"1167\">precisa<\/em> conhecer o irm\u00e3o da Naomi&#8230;<\/span><\/p>\n<p dir=\"ltr\" data-placeholder=\"Tradu\u00e7\u00e3o\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif; color: #000000; font-size: 18pt;\"><em><strong>Uma P\u00e9rola da Sabedoria Judaica<\/strong><\/em><\/span><br \/>\n<span style=\"font-family: tahoma, arial, helvetica, sans-serif; color: #000000; font-size: 18pt;\"><em><span lang=\"pt-BR\">\u2014 \u201cO dissabor faz no homem o que a ferrugem faz no ferro.\u201d<\/span><span lang=\"pt\">\u00a0<\/span><\/em><\/span><\/p>\n<p><span style=\"font-size: 18pt; font-family: terminal, monaco, monospace; color: #000000;\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif;\"><em><strong>Frases dos Melhores Humoristas Judeus<\/strong><strong><br \/>\n<\/strong><\/em><b><strong>Sophie Tucker (<em>Sonya Kalish \u2013 Tulchyn, Russia \u2013 13\/1\/1887 \u2013 Nova York, 9\/2\/1966<\/em><i>)<\/i><\/strong><\/b><em><strong><b><br \/>\n<\/b><\/strong>\u2014 \u201cAte os 18 anos uma mulher precisa ter bons pais; dos 19 aos 35, boa apar\u00eancia; dos 35 aos 55, boa personalidade; e dos 55 em diante, de dinheiro.\u201d<\/em><\/span><br \/>\n<\/span><\/p>\n<p><span style=\"font-size: 18pt; font-family: tahoma, arial, helvetica, sans-serif; color: #000000;\"><em><strong>As Terr\u00edveis Pragas Judaicas<br \/>\n<\/strong>\u2014 \u201cQue voc\u00ea se torne ateu e case com uma mulher piedosa.\u201d<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"26151\" data-permalink=\"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/reduzir-9\/\" data-orig-file=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-8.jpg?fit=600%2C400&amp;ssl=1\" data-orig-size=\"600,400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"REDUZIR\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-8.jpg?fit=600%2C400&amp;ssl=1\" class=\"alignnone size-full wp-image-26151\" src=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-8.jpg?resize=600%2C400&#038;ssl=1\" alt=\"\" width=\"600\" height=\"400\" srcset=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-8.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-8.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><br \/>\n<a href=\"https:\/\/unsplash.com\/pt-br\/fotografias\/um-noivo-coloca-um-anel-no-dedo-de-uma-noiva-opBS-42NrgY\"><span style=\"color: #0000ff; font-size: 14pt;\"><em><strong>Foto: Unsplash<\/strong><\/em><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma Casamenteira Nunca Perde o Fregu\u00eas Durante o servi\u00e7o na sinagoga que frequentava, Dona Leah, uma casamenteira &#8216;das antigas&#8217; n\u00e3o conseguiu deixar de notar um jovem simp\u00e1tico entrando no templo. Ela nunca o tinha visto antes, ent\u00e3o, ao final do servi\u00e7o, foi at\u00e9 ele e se apresentou.\u2014 Ol\u00e1, eu sou Leah Gold \u2014 disse. \u2014 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":26150,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-26132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sexta do Humor e da Cultura Judaica - Uma Casamenteira Nunca Perde o Fregu\u00eas | Blog do Guelmann<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sexta do Humor e da Cultura Judaica - Uma Casamenteira Nunca Perde o Fregu\u00eas | Blog do Guelmann\" \/>\n<meta property=\"og:description\" content=\"Uma Casamenteira Nunca Perde o Fregu\u00eas Durante o servi\u00e7o na sinagoga que frequentava, Dona Leah, uma casamenteira &#8216;das antigas&#8217; n\u00e3o conseguiu deixar de notar um jovem simp\u00e1tico entrando no templo. Ela nunca o tinha visto antes, ent\u00e3o, ao final do servi\u00e7o, foi at\u00e9 ele e se apresentou.\u2014 Ol\u00e1, eu sou Leah Gold \u2014 disse. \u2014 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Guelmann\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-11T20:22:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-17T11:55:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gerson Guelmann zs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gerson Guelmann zs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/uma-casamenteira-nunca-perde-o-fregues\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/uma-casamenteira-nunca-perde-o-fregues\\\/\"},\"author\":{\"name\":\"Gerson Guelmann zs\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\"},\"headline\":\"Sexta do Humor e da Cultura Judaica &#8211; Uma Casamenteira Nunca Perde o Fregu\u00eas\",\"datePublished\":\"2025-07-11T20:22:30+00:00\",\"dateModified\":\"2025-07-17T11:55:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/uma-casamenteira-nunca-perde-o-fregues\\\/\"},\"wordCount\":313,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/uma-casamenteira-nunca-perde-o-fregues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/REDUZIR-7.jpg?fit=600%2C400&ssl=1\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/uma-casamenteira-nunca-perde-o-fregues\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/uma-casamenteira-nunca-perde-o-fregues\\\/\",\"url\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/uma-casamenteira-nunca-perde-o-fregues\\\/\",\"name\":\"Sexta do Humor e da Cultura Judaica - Uma Casamenteira Nunca Perde o Fregu\u00eas | Blog do Guelmann\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/uma-casamenteira-nunca-perde-o-fregues\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/uma-casamenteira-nunca-perde-o-fregues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/REDUZIR-7.jpg?fit=600%2C400&ssl=1\",\"datePublished\":\"2025-07-11T20:22:30+00:00\",\"dateModified\":\"2025-07-17T11:55:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/uma-casamenteira-nunca-perde-o-fregues\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/uma-casamenteira-nunca-perde-o-fregues\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/REDUZIR-7.jpg?fit=600%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/REDUZIR-7.jpg?fit=600%2C400&ssl=1\",\"width\":600,\"height\":400},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/\",\"name\":\"Blog do Guelmann\",\"description\":\"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\",\"name\":\"Gerson Guelmann zs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"caption\":\"Gerson Guelmann zs\"},\"description\":\"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sexta do Humor e da Cultura Judaica - Uma Casamenteira Nunca Perde o Fregu\u00eas | Blog do Guelmann","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/","og_locale":"pt_BR","og_type":"article","og_title":"Sexta do Humor e da Cultura Judaica - Uma Casamenteira Nunca Perde o Fregu\u00eas | Blog do Guelmann","og_description":"Uma Casamenteira Nunca Perde o Fregu\u00eas Durante o servi\u00e7o na sinagoga que frequentava, Dona Leah, uma casamenteira &#8216;das antigas&#8217; n\u00e3o conseguiu deixar de notar um jovem simp\u00e1tico entrando no templo. Ela nunca o tinha visto antes, ent\u00e3o, ao final do servi\u00e7o, foi at\u00e9 ele e se apresentou.\u2014 Ol\u00e1, eu sou Leah Gold \u2014 disse. \u2014 [&hellip;]","og_url":"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/","og_site_name":"Blog do Guelmann","article_published_time":"2025-07-11T20:22:30+00:00","article_modified_time":"2025-07-17T11:55:49+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-7.jpg","type":"image\/jpeg"}],"author":"Gerson Guelmann zs","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gerson Guelmann zs","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/#article","isPartOf":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/"},"author":{"name":"Gerson Guelmann zs","@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e"},"headline":"Sexta do Humor e da Cultura Judaica &#8211; Uma Casamenteira Nunca Perde o Fregu\u00eas","datePublished":"2025-07-11T20:22:30+00:00","dateModified":"2025-07-17T11:55:49+00:00","mainEntityOfPage":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/"},"wordCount":313,"commentCount":0,"image":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-7.jpg?fit=600%2C400&ssl=1","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/","url":"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/","name":"Sexta do Humor e da Cultura Judaica - Uma Casamenteira Nunca Perde o Fregu\u00eas | Blog do Guelmann","isPartOf":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/#primaryimage"},"image":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-7.jpg?fit=600%2C400&ssl=1","datePublished":"2025-07-11T20:22:30+00:00","dateModified":"2025-07-17T11:55:49+00:00","author":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gersonguelmann.com.br\/blog\/uma-casamenteira-nunca-perde-o-fregues\/#primaryimage","url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-7.jpg?fit=600%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-7.jpg?fit=600%2C400&ssl=1","width":600,"height":400},{"@type":"WebSite","@id":"https:\/\/gersonguelmann.com.br\/blog\/#website","url":"https:\/\/gersonguelmann.com.br\/blog\/","name":"Blog do Guelmann","description":"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gersonguelmann.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e","name":"Gerson Guelmann zs","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","caption":"Gerson Guelmann zs"},"description":"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei."}]}},"views":23,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-7.jpg?fit=600%2C400&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p96e7O-6Nu","jetpack-related-posts":[{"id":1078,"url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-39\/","url_meta":{"origin":26132,"position":0},"title":"Tr\u00eas na Quarta de Humor Judaico","author":"Gerson Guelmann zs","date":"28 de maio de 2025","format":false,"excerpt":"Uma Sinagoga Como Nenhuma Outra Certa sinagoga em Nova York era famosa por sua exclusividade, especialmente porque todos os frequentadores eram altos executivos, banqueiros, etc. Um judeu em situa\u00e7\u00e3o de rua entrou, querendo rezar, e pediu ao rabino para se tornar membro. Sem saber como recusar, o rabino sugeriu: \u2014\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/05\/2805-1.jpg?fit=500%2C356&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":26475,"url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-66\/","url_meta":{"origin":26132,"position":1},"title":"Tr\u00eas na Quarta de Humor Judaico","author":"Gerson Guelmann zs","date":"10 de dezembro de 2025","format":false,"excerpt":"O Velho Samuel, o M\u00e9dico e o Ca\u00e7ador de Ursos Samuel, um idoso de 89 anos, estava fazendo seu exame m\u00e9dico anual. O Dr. Boris, que o atendia h\u00e1 muitos anos,\u00a0perguntou como ele estava se sentindo: - Nunca estive t\u00e3o bem. N\u00e3o sei se o senhor sabe, mas casei outra\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/12\/HojePR-4.png?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/12\/HojePR-4.png?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/12\/HojePR-4.png?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/12\/HojePR-4.png?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/12\/HojePR-4.png?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":22659,"url":"https:\/\/gersonguelmann.com.br\/blog\/a-casamenteira-e-seu-assistente\/","url_meta":{"origin":26132,"position":2},"title":"A Casamenteira e Seu Assistente","author":"Gerson Guelmann zs","date":"29 de janeiro de 2022","format":false,"excerpt":"A Casamenteira judia da aldeia estava ficando velha e n\u00e3o podia mais se locomover como costumava fazer. Depois de pensar muito ela concluiu que estava na hora de contratar um jovem assistente que a conduziria na carro\u00e7a e a ajudaria nas visitas \u00e0s fam\u00edlias dos patr\u00edcios, para mais tarde assumir\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2022\/01\/CASAMENTO-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2022\/01\/CASAMENTO-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2022\/01\/CASAMENTO-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2022\/01\/CASAMENTO-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2022\/01\/CASAMENTO-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":22493,"url":"https:\/\/gersonguelmann.com.br\/blog\/pilulas-de-humor-judaico-35\/","url_meta":{"origin":26132,"position":3},"title":"P\u00edlulas de Humor Judaico (35)","author":"Gerson Guelmann zs","date":"20 de outubro de 2021","format":false,"excerpt":"O A\u00e7ougueiro Moishe e a Proposta de Casamento Rivke, a casamenteira de uma pequena cidade na Polonia, entrou no a\u00e7ougue de Moishe, um solteir\u00e3o j\u00e1 com certa idade, t\u00e3o feio que seu apelido entre os judeus era \"Moishe Horroroso\". Assim que ela entrou o a\u00e7ougueiro perguntou: - \"O que voc\u00ea\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2021\/10\/GRAVIDA.jpg?fit=800%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2021\/10\/GRAVIDA.jpg?fit=800%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2021\/10\/GRAVIDA.jpg?fit=800%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2021\/10\/GRAVIDA.jpg?fit=800%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26178,"url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-47\/","url_meta":{"origin":26132,"position":4},"title":"Tr\u00eas na Quarta de Humor Judaico","author":"Gerson Guelmann zs","date":"30 de julho de 2025","format":false,"excerpt":"Revela\u00e7\u00f5es Na Lua de Mel Ezra e Leah se casaram e, na primeira noite na cama, ele a abra\u00e7ou com carinho e sussurrou docemente: \u2014 Leah, querida, por favor, levante sua camisola. Muito docemente, ela respondeu: \u2014 N\u00e3\u00e3\u00e3o... Ezra insistiu, agora um pouco mais firme: \u2014 Leah, levante a camisola.\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/HojePR-21.jpg?fit=480%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5629,"url":"https:\/\/gersonguelmann.com.br\/blog\/os-tres-judeus-e-o-assalto-na-saida-da-sinagoga\/","url_meta":{"origin":26132,"position":5},"title":"Os Tr\u00eas Judeus e o Assalto na Sa\u00edda da Sinagoga","author":"Gerson Guelmann zs","date":"17 de setembro de 2019","format":false,"excerpt":"O rabino, o cantor lit\u00fargico e o presidente da entidade mantenedora de uma Sinagoga estavam saindo do pr\u00e9dio quando foram assaltados, colocados num carro e levados para fora da cidade. Os bandidos pediram que entregassem dinheiro, j\u00f3ias e todos os objetos de valor que tinham no carro. Quando responderam que\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/12\/Assalto-300x166.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts\/26132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/comments?post=26132"}],"version-history":[{"count":0,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts\/26132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/media\/26150"}],"wp:attachment":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/media?parent=26132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/categories?post=26132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/tags?post=26132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}