    {"id":26193,"date":"2025-08-06T19:37:29","date_gmt":"2025-08-06T22:37:29","guid":{"rendered":"https:\/\/gersonguelmann.com.br\/blog\/?p=26193"},"modified":"2025-08-08T15:34:35","modified_gmt":"2025-08-08T18:34:35","slug":"tres-na-quarta-de-humor-judaico-48","status":"publish","type":"post","link":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/","title":{"rendered":"Tr\u00eas na Quarta de Humor Judaico"},"content":{"rendered":"<p data-start=\"210\" data-end=\"233\"><em><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong data-start=\"210\" data-end=\"233\">Um Ano Intermin\u00e1vel<br \/>\n<\/strong><\/span><\/em><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Moishe Kaplan foi ao m\u00e9dico, que lhe disse que ele estava com uma doen\u00e7a grave e teria apenas um ano de vida. Abalado com a not\u00edcia, Moishe decidiu procurar seu mentor espiritual, o Rabino Feldman, para conversar. Depois de explicar sua situa\u00e7\u00e3o, perguntou ao rabino se havia algo que pudesse fazer.<br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">&#8211; <em>Olha &#8211; disse ele -, o que voc\u00ea deve fazer \u00e9 sair por a\u00ed, procurar e casar com a mulher mais rabugenta que encontrar. Isso \u00e9 importante<\/em> &#8211; enfatizou o Rabino Feldman.<\/span><br data-start=\"704\" data-end=\"707\" \/><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">E, sem levar em conta o olhar espantado de Moishe, continuou:<\/span><br data-start=\"768\" data-end=\"771\" \/><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">&#8211; <em>E, depois, mudar para um apartamento acima de um abatedouro de frangos e tamb\u00e9m come\u00e7ar a arrecadar dinheiro para as obras sociais da nossa sinagoga<\/em>.<br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Moishe perguntou, ou melhor, comentou, sem entender:<br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">&#8211; <em>Espere, rabino&#8230; Isso vai prolongar minha vida?<\/em><br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">&#8211; <em>N\u00e3o<\/em> &#8211; respondeu o religioso -, <em>mas vai fazer o tempo que te resta parecer uma eternidade<\/em>.<\/span><\/p>\n<p data-start=\"1127\" data-end=\"1156\"><em><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong data-start=\"1127\" data-end=\"1156\">Um F de Falta de Vergonha<br \/>\n<\/strong><\/span><\/em><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">O pequeno Yossele chegou em casa vindo da escola e apresentou o boletim ao pai. Ap\u00f3s alguns segundos, olhando muito s\u00e9rio para ele, o pai perguntou:<br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">&#8211; <em>Me explique: o que aconteceu para que voc\u00ea tirasse a letra F?<\/em><br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Como era a primeira vez que havia tirado F &#8211; a pior nota de todas &#8211; Yossele, tentando enganar o pai, explicou:<br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">&#8211; <em>N\u00e3o \u00e9 nota, \u00e9 &#8220;F&#8221; de falta, pai&#8230;<\/em><br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">&#8211; <em>Espere um pouco&#8230;<\/em> &#8211; disse o pai &#8211; <em>Voc\u00ea faltou justamente no dia da prova?<\/em><br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Sem sa\u00edda, o menino confessou:<br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">&#8211; <em>N\u00e3o&#8230; mas o menino que senta ao meu lado faltou.<\/em><\/span><\/p>\n<p data-start=\"1686\" data-end=\"1710\"><em><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong data-start=\"1686\" data-end=\"1710\">Um Assento na Janela<br \/>\n<\/strong><\/span><\/em><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Moishe e Miriam decidiram passar o ver\u00e3o viajando de carro por toda a Europa. No final das f\u00e9rias, devolveram o carro na locadora, no aeroporto, e, quando foram fazer o check-in, Miriam pediu assentos na janela para ela e para Moishe.<br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">O funcion\u00e1rio entendeu que devia alert\u00e1-la para o fato de que seria uma viagem de algumas horas, e que isso os impediria de estarem juntos.<br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">\u2014 <em>Meu querido \u2014 <\/em>disse Miriam<em> \u2014, eu acabei de passar quatro semanas espremida em um carro compacto com esse homem. Pode ter certeza, eu sei por que estou pedindo.<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" height=\"200\" width=\"300\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-22.jpg?resize=300%2C200&#038;ssl=1\" \/><br \/>\n<span style=\"font-size: 14pt; font-family: tahoma, arial, helvetica, sans-serif;\"><em><strong><a href=\"https:\/\/unsplash.com\/pt-br\/fotografias\/mulher-andando-no-aviao-enquanto-observa-na-janela-APHuyhlnEuc\"><span style=\"color: #0000ff;\">Foto: Unsplash<\/span><\/a><\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um Ano Intermin\u00e1vel Moishe Kaplan foi ao m\u00e9dico, que lhe disse que ele estava com uma doen\u00e7a grave e teria apenas um ano de vida. Abalado com a not\u00edcia, Moishe decidiu procurar seu mentor espiritual, o Rabino Feldman, para conversar. Depois de explicar sua situa\u00e7\u00e3o, perguntou ao rabino se havia algo que pudesse fazer. &#8211; [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":26236,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-26193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tr\u00eas na Quarta de Humor Judaico | Blog do Guelmann<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tr\u00eas na Quarta de Humor Judaico | Blog do Guelmann\" \/>\n<meta property=\"og:description\" content=\"Um Ano Intermin\u00e1vel Moishe Kaplan foi ao m\u00e9dico, que lhe disse que ele estava com uma doen\u00e7a grave e teria apenas um ano de vida. Abalado com a not\u00edcia, Moishe decidiu procurar seu mentor espiritual, o Rabino Feldman, para conversar. Depois de explicar sua situa\u00e7\u00e3o, perguntou ao rabino se havia algo que pudesse fazer. &#8211; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Guelmann\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-06T22:37:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-08T18:34:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gerson Guelmann zs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gerson Guelmann zs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-48\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-48\\\/\"},\"author\":{\"name\":\"Gerson Guelmann zs\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\"},\"headline\":\"Tr\u00eas na Quarta de Humor Judaico\",\"datePublished\":\"2025-08-06T22:37:29+00:00\",\"dateModified\":\"2025-08-08T18:34:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-48\\\/\"},\"wordCount\":384,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-48\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/HojePR-22.jpg?fit=900%2C600&ssl=1\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-48\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-48\\\/\",\"url\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-48\\\/\",\"name\":\"Tr\u00eas na Quarta de Humor Judaico | Blog do Guelmann\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-48\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-48\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/HojePR-22.jpg?fit=900%2C600&ssl=1\",\"datePublished\":\"2025-08-06T22:37:29+00:00\",\"dateModified\":\"2025-08-08T18:34:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-48\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-48\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/HojePR-22.jpg?fit=900%2C600&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/HojePR-22.jpg?fit=900%2C600&ssl=1\",\"width\":900,\"height\":600},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/\",\"name\":\"Blog do Guelmann\",\"description\":\"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\",\"name\":\"Gerson Guelmann zs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"caption\":\"Gerson Guelmann zs\"},\"description\":\"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tr\u00eas na Quarta de Humor Judaico | Blog do Guelmann","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/","og_locale":"pt_BR","og_type":"article","og_title":"Tr\u00eas na Quarta de Humor Judaico | Blog do Guelmann","og_description":"Um Ano Intermin\u00e1vel Moishe Kaplan foi ao m\u00e9dico, que lhe disse que ele estava com uma doen\u00e7a grave e teria apenas um ano de vida. Abalado com a not\u00edcia, Moishe decidiu procurar seu mentor espiritual, o Rabino Feldman, para conversar. Depois de explicar sua situa\u00e7\u00e3o, perguntou ao rabino se havia algo que pudesse fazer. &#8211; [&hellip;]","og_url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/","og_site_name":"Blog do Guelmann","article_published_time":"2025-08-06T22:37:29+00:00","article_modified_time":"2025-08-08T18:34:35+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-22.jpg","type":"image\/jpeg"}],"author":"Gerson Guelmann zs","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gerson Guelmann zs","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/#article","isPartOf":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/"},"author":{"name":"Gerson Guelmann zs","@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e"},"headline":"Tr\u00eas na Quarta de Humor Judaico","datePublished":"2025-08-06T22:37:29+00:00","dateModified":"2025-08-08T18:34:35+00:00","mainEntityOfPage":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/"},"wordCount":384,"commentCount":0,"image":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-22.jpg?fit=900%2C600&ssl=1","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/","url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/","name":"Tr\u00eas na Quarta de Humor Judaico | Blog do Guelmann","isPartOf":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/#primaryimage"},"image":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-22.jpg?fit=900%2C600&ssl=1","datePublished":"2025-08-06T22:37:29+00:00","dateModified":"2025-08-08T18:34:35+00:00","author":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-48\/#primaryimage","url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-22.jpg?fit=900%2C600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-22.jpg?fit=900%2C600&ssl=1","width":900,"height":600},{"@type":"WebSite","@id":"https:\/\/gersonguelmann.com.br\/blog\/#website","url":"https:\/\/gersonguelmann.com.br\/blog\/","name":"Blog do Guelmann","description":"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gersonguelmann.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e","name":"Gerson Guelmann zs","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","caption":"Gerson Guelmann zs"},"description":"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei."}]}},"views":9,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-22.jpg?fit=900%2C600&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p96e7O-6Ot","jetpack-related-posts":[{"id":26129,"url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-44\/","url_meta":{"origin":26193,"position":0},"title":"Tr\u00eas na Quarta de Humor Judaico","author":"Gerson Guelmann zs","date":"9 de julho de 2025","format":false,"excerpt":"O Rabino e o Imposto de Renda O rabino Rosenberg estava na secretaria da sinagoga quando o telefone tocou: \u2014 Boa tarde, \u00e9 o rabino Rosenberg?\u2014 Sim, sou eu mesmo.\u2014 Sou da Delegacia da Receita Federal e gostaria de saber se o senhor pode nos ajudar.\u2014 Sim, claro. \u00c9 minha\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-3.jpg?fit=600%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-3.jpg?fit=600%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-3.jpg?fit=600%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":25257,"url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-35\/","url_meta":{"origin":26193,"position":1},"title":"Tr\u00eas na Quarta de Humor Judaico","author":"Gerson Guelmann zs","date":"30 de abril de 2025","format":false,"excerpt":"Moishe e Sua Brincadeira Sexual Moishe, cheio de amor para dar, olhou para a esposa e disse:\u2014 Ruth, acho que a gente devia apimentar um pouco nossa vida \u00edntima. Pod\u00edamos fazer um joguinho de faz de conta, uma encena\u00e7\u00e3o.Mesmo sem nenhuma disposi\u00e7\u00e3o para o sexo e j\u00e1 pensando em como\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/04\/HojePR-38.jpg?fit=600%2C450&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/04\/HojePR-38.jpg?fit=600%2C450&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/04\/HojePR-38.jpg?fit=600%2C450&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":129,"url":"https:\/\/gersonguelmann.com.br\/blog\/pilulas-de-humor-judaico-14\/","url_meta":{"origin":26193,"position":2},"title":"P\u00edlulas de Humor Judaico (14)","author":"Gerson Guelmann zs","date":"17 de mar\u00e7o de 2021","format":false,"excerpt":"Quest\u00e3o de Sorte Jac\u00f3 e Abra\u00e3o estavam discutindo sobre a vida. Um deles suspirou e disse para o outro: - \u201cConsiderando o qu\u00e3o dura \u00e9 a vida, a morte n\u00e3o \u00e9 assim t\u00e3o ruim, n\u00e9? Na verdade, \u00e0s vezes acho que seria melhor n\u00e3o ter nascido\u201d. - \"\u00c9 verdade\", respondeu\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/06\/agente-secreto.jpg?fit=960%2C667&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/06\/agente-secreto.jpg?fit=960%2C667&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/06\/agente-secreto.jpg?fit=960%2C667&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/06\/agente-secreto.jpg?fit=960%2C667&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":23931,"url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-22\/","url_meta":{"origin":26193,"position":3},"title":"Tr\u00eas na Quarta de Humor Judaico","author":"Gerson Guelmann zs","date":"29 de janeiro de 2025","format":false,"excerpt":"O Rabino, a Not\u00edcia da Morte e o \u00daltimo Pedido O Rabino\u00a0estava em seu escrit\u00f3rio na Sinagoga preparando sua pr\u00e9dica do Shabbat, quando a senhora Miriam\u00a0aproximou-se, em l\u00e1grimas. Vendo que a mulher estava descontrolada, o Rabino segurou suas m\u00e3os e perguntou: \u2013\u00a0\u201cO que houve? O que posso fazer por voc\u00ea?\u201d\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/01\/FOTO-1-2.jpg?fit=1200%2C795&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/01\/FOTO-1-2.jpg?fit=1200%2C795&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/01\/FOTO-1-2.jpg?fit=1200%2C795&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/01\/FOTO-1-2.jpg?fit=1200%2C795&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/01\/FOTO-1-2.jpg?fit=1200%2C795&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":26415,"url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-60\/","url_meta":{"origin":26193,"position":4},"title":"Tr\u00eas na Quarta de Humor Judaico","author":"Gerson Guelmann zs","date":"29 de outubro de 2025","format":false,"excerpt":"Aconselhamento Matrimonial O Rabino deu a um homem um conselho de casamento: que sua esposa ficasse encarregada das pequenas decis\u00f5es, e ele, das grandes.Depois de trinta anos, Saul, o marido, voltou ao Rabino reclamando:- Em trinta anos, n\u00e3o houve nenhuma grande decis\u00e3o! Ela simplesmente ignorou o seu conselho e n\u00e3o\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/10\/HojePR-15.jpg?fit=600%2C450&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/10\/HojePR-15.jpg?fit=600%2C450&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/10\/HojePR-15.jpg?fit=600%2C450&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":26043,"url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-41\/","url_meta":{"origin":26193,"position":5},"title":"Tr\u00eas na Quarta de Humor Judaico","author":"Gerson Guelmann zs","date":"11 de junho de 2025","format":false,"excerpt":"Vai Fazer Compras com a Esposa? Preste Aten\u00e7\u00e3o!Rubens foi fazer compras com a esposa, Golda, mas, assim como acontece com muitos maridos, sua paci\u00eancia para essa atividade era escassa. Golda queria aproveitar a liquida\u00e7\u00e3o de roupas em um shopping e, por isso, ele j\u00e1 estava h\u00e1 mais de uma hora\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/06\/HojePR-13.jpg?fit=606%2C405&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/06\/HojePR-13.jpg?fit=606%2C405&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/06\/HojePR-13.jpg?fit=606%2C405&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts\/26193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/comments?post=26193"}],"version-history":[{"count":0,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts\/26193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/media\/26236"}],"wp:attachment":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/media?parent=26193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/categories?post=26193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/tags?post=26193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}