    {"id":26196,"date":"2025-08-08T15:40:21","date_gmt":"2025-08-08T18:40:21","guid":{"rendered":"https:\/\/gersonguelmann.com.br\/blog\/?p=26196"},"modified":"2025-08-08T15:50:50","modified_gmt":"2025-08-08T18:50:50","slug":"sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins","status":"publish","type":"post","link":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/","title":{"rendered":"Sexta do Humor e da Cultura Judaica &#8211; At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins"},"content":{"rendered":"<article class=\"text-token-text-primary w-full focus:outline-none scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"cff0025d-f95d-47d2-a1fc-835c75888397\" data-testid=\"conversation-turn-2\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] @[37rem]:[--thread-content-margin:--spacing(6)] @[72rem]:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:32rem] @[34rem]:[--thread-content-max-width:40rem] @[64rem]:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"5496655c-784e-48c6-bf02-196a5a2c00cd\" data-message-model-slug=\"gpt-4o\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\n<p data-start=\"0\" data-end=\"122\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><em><strong>At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins<\/strong><\/em><br \/>\nNa casa de repouso mantida pela comunidade judaica, alguns idosos estavam reunidos. Alguns se entretinham jogando xadrez e outros conversavam sobre os chamados &#8216;achaques da velhice&#8217;, suas dores e limita\u00e7\u00f5es.<br \/>\n&#8211; <em>Meus bra\u00e7os est\u00e3o t\u00e3o fracos que levantar esta x\u00edcara de caf\u00e9 \u00e9 um sacrif\u00edcio<\/em> &#8211; disse Applebaum.<br \/>\n&#8211; <em>Sei como \u00e9. Minha catarata est\u00e1 t\u00e3o avan\u00e7ada que eu nem consigo ver meu caf\u00e9<\/em> &#8211; respondeu Shiffman.<br \/>\n&#8211; <em>N\u00e3o consigo virar a cabe\u00e7a por causa da artrite no pesco\u00e7o<\/em> \u2013 comentou Markewitz, e v\u00e1rios assentiram com a cabe\u00e7a, lentamente.<br \/>\n&#8211; <em>Meus comprimidos para press\u00e3o me deixam tonto<\/em> \u2013 contribuiu Himmlefarb.<br \/>\n&#8211; <em>Caminhar at\u00e9 aqui foi um tormento, meus joelhos me matam<\/em> &#8211; falou Katz.<br \/>\n&#8211; <em>Voc\u00eas se queixam sem raz\u00e3o, n\u00e3o sabem o que \u00e9 sofrer de pris\u00e3o de ventre<\/em> &#8211; emendou Rifkin.<br \/>\n&#8211; <em>Acho que esse \u00e9 o pre\u00e7o que pagamos por envelhecer<\/em> \u2013 lamentou Goldberg, balan\u00e7ando a cabe\u00e7a com dificuldade.<br \/>\nEnt\u00e3o, por um instante, fez-se sil\u00eancio.<br \/>\n&#8211; <em>Bem, n\u00e3o \u00e9 t\u00e3o ruim assim, pessoal<\/em> &#8211; disse Rosenbloom, animado. &#8211; <em>Gra\u00e7as a Deus, ainda temos carteira de motorista e todos podemos dirigir<\/em>.<\/span><\/p>\n<p dir=\"ltr\" data-placeholder=\"Tradu\u00e7\u00e3o\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif; color: #000000; font-size: 18pt;\"><em><strong>Uma P\u00e9rola da Sabedoria Judaica<\/strong><\/em><\/span><br \/>\n<span style=\"font-family: tahoma, arial, helvetica, sans-serif; color: #000000; font-size: 18pt;\"><em><span lang=\"pt-BR\">&#8211; \u201c\u00c0s vezes uma pessoa pode ser mais forte do que o ferro e mais fraca do que uma mosca.\u201d<\/span><span lang=\"pt\">\u00a0<\/span><\/em><\/span><\/p>\n<p><span style=\"font-size: 18pt; font-family: tahoma, arial, helvetica, sans-serif; color: #000000;\"><em><strong>Frases dos Melhores Humoristas Judeus<\/strong><strong><br \/>\n<\/strong><\/em><em><strong><b>Woody Allen\u00a0(<i>Allan Stewart K\u00f6nigsberg \u2013 Nova York, 1\/12\/1935)<\/i><br \/>\n<\/b><\/strong>&#8211; \u201c\u00c9 muito dif\u00edcil que teu cora\u00e7\u00e3o e teu c\u00e9rebro trabalhem juntos. No meu caso, eles n\u00e3o s\u00e3o nem amigos.\u201d<\/em><br \/>\n<\/span><\/p>\n<p><span style=\"font-size: 18pt; font-family: tahoma, arial, helvetica, sans-serif; color: #000000;\"><em><strong>As Terr\u00edveis Pragas Judaicas<br \/>\n<\/strong>&#8211; &#8220;Que voc\u00ea tenha uma longa noite de sono e teus sonhos sejam s\u00f3 sobre os teus problemas<span lang=\"pt-PT\">.<\/span>\u201d<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"26238\" data-permalink=\"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/hojepr-509\/\" data-orig-file=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-24.jpg?fit=600%2C400&amp;ssl=1\" data-orig-size=\"600,400\" data-comments-opened=\"1\" data-image-title=\"HojePR\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-24.jpg?fit=600%2C400&amp;ssl=1\" class=\"alignnone size-full wp-image-26238\" src=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-24.jpg?resize=600%2C400&#038;ssl=1\" alt=\"\" width=\"600\" height=\"400\" srcset=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-24.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-24.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><br \/>\n<a href=\"https:\/\/unsplash.com\/pt-br\/fotografias\/dois-homens-jogando-xadrez-em-lente-de-foco-raso-P0F_zH39qhs\"><span style=\"font-size: 14pt; font-family: georgia, palatino, serif; color: #0000ff;\"><em><strong>Foto: Unsplash<\/strong><\/em><\/span><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"flex min-h-[46px] justify-start\">\n<div class=\"touch:-me-2 touch:-ms-3.5 -ms-2.5 -me-1 flex flex-wrap items-center gap-y-4 p-1 select-none touch:w-[calc(100%+--spacing(3.5))] -mt-1 w-[calc(100%+--spacing(2.5))] duration-[1.5s] focus-within:transition-none hover:transition-none pointer-events-none [mask-image:linear-gradient(to_right,black_33%,transparent_66%)] [mask-size:300%_100%] [mask-position:100%_0%] motion-safe:transition-[mask-position] group-hover\/turn-messages:pointer-events-auto group-hover\/turn-messages:[mask-position:0_0] group-focus-within\/turn-messages:pointer-events-auto group-focus-within\/turn-messages:[mask-position:0_0] has-data-[state=open]:pointer-events-auto has-data-[state=open]:[mask-position:0_0]\">\n<p>&nbsp;<\/p>\n<div class=\"flex items-center\"><\/div>\n<div class=\"grow\"><\/div>\n<\/div>\n<\/div>\n<div class=\"aria-live=polite absolute select-none\">\n<div class=\"flex items-center justify-center\"><span class=\"flex items-center gap-1.5 select-none\"><span class=\"whitespace-nowrap! select-none max-md:sr-only\">Perguntar ao ChatGPT<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<div class=\"pointer-events-none h-px w-px\" aria-hidden=\"true\" data-edge=\"true\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins Na casa de repouso mantida pela comunidade judaica, alguns idosos estavam reunidos. Alguns se entretinham jogando xadrez e outros conversavam sobre os chamados &#8216;achaques da velhice&#8217;, suas dores e limita\u00e7\u00f5es. &#8211; Meus bra\u00e7os est\u00e3o t\u00e3o fracos que levantar esta x\u00edcara de caf\u00e9 \u00e9 um sacrif\u00edcio &#8211; disse [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":26239,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-26196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sexta do Humor e da Cultura Judaica - At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins | Blog do Guelmann<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sexta do Humor e da Cultura Judaica - At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins | Blog do Guelmann\" \/>\n<meta property=\"og:description\" content=\"At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins Na casa de repouso mantida pela comunidade judaica, alguns idosos estavam reunidos. Alguns se entretinham jogando xadrez e outros conversavam sobre os chamados &#8216;achaques da velhice&#8217;, suas dores e limita\u00e7\u00f5es. &#8211; Meus bra\u00e7os est\u00e3o t\u00e3o fracos que levantar esta x\u00edcara de caf\u00e9 \u00e9 um sacrif\u00edcio &#8211; disse [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Guelmann\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-08T18:40:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-08T18:50:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gerson Guelmann zs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gerson Guelmann zs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\\\/\"},\"author\":{\"name\":\"Gerson Guelmann zs\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\"},\"headline\":\"Sexta do Humor e da Cultura Judaica &#8211; At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins\",\"datePublished\":\"2025-08-08T18:40:21+00:00\",\"dateModified\":\"2025-08-08T18:50:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\\\/\"},\"wordCount\":323,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/HojePR-25.jpg?fit=600%2C400&ssl=1\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\\\/\",\"url\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\\\/\",\"name\":\"Sexta do Humor e da Cultura Judaica - At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins | Blog do Guelmann\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/HojePR-25.jpg?fit=600%2C400&ssl=1\",\"datePublished\":\"2025-08-08T18:40:21+00:00\",\"dateModified\":\"2025-08-08T18:50:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/HojePR-25.jpg?fit=600%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/HojePR-25.jpg?fit=600%2C400&ssl=1\",\"width\":600,\"height\":400},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/\",\"name\":\"Blog do Guelmann\",\"description\":\"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\",\"name\":\"Gerson Guelmann zs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"caption\":\"Gerson Guelmann zs\"},\"description\":\"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.\",\"sameAs\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sexta do Humor e da Cultura Judaica - At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins | Blog do Guelmann","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/","og_locale":"pt_BR","og_type":"article","og_title":"Sexta do Humor e da Cultura Judaica - At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins | Blog do Guelmann","og_description":"At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins Na casa de repouso mantida pela comunidade judaica, alguns idosos estavam reunidos. Alguns se entretinham jogando xadrez e outros conversavam sobre os chamados &#8216;achaques da velhice&#8217;, suas dores e limita\u00e7\u00f5es. &#8211; Meus bra\u00e7os est\u00e3o t\u00e3o fracos que levantar esta x\u00edcara de caf\u00e9 \u00e9 um sacrif\u00edcio &#8211; disse [&hellip;]","og_url":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/","og_site_name":"Blog do Guelmann","article_published_time":"2025-08-08T18:40:21+00:00","article_modified_time":"2025-08-08T18:50:50+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-25.jpg","type":"image\/jpeg"}],"author":"Gerson Guelmann zs","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gerson Guelmann zs","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/#article","isPartOf":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/"},"author":{"name":"Gerson Guelmann zs","@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e"},"headline":"Sexta do Humor e da Cultura Judaica &#8211; At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins","datePublished":"2025-08-08T18:40:21+00:00","dateModified":"2025-08-08T18:50:50+00:00","mainEntityOfPage":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/"},"wordCount":323,"commentCount":0,"image":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-25.jpg?fit=600%2C400&ssl=1","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/","url":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/","name":"Sexta do Humor e da Cultura Judaica - At\u00e9 Que as Coisas N\u00e3o Est\u00e3o T\u00e3o Ruins | Blog do Guelmann","isPartOf":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/#primaryimage"},"image":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-25.jpg?fit=600%2C400&ssl=1","datePublished":"2025-08-08T18:40:21+00:00","dateModified":"2025-08-08T18:50:50+00:00","author":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-ate-que-as-coisas-nao-estao-tao-ruins\/#primaryimage","url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-25.jpg?fit=600%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-25.jpg?fit=600%2C400&ssl=1","width":600,"height":400},{"@type":"WebSite","@id":"https:\/\/gersonguelmann.com.br\/blog\/#website","url":"https:\/\/gersonguelmann.com.br\/blog\/","name":"Blog do Guelmann","description":"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gersonguelmann.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e","name":"Gerson Guelmann zs","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","caption":"Gerson Guelmann zs"},"description":"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.","sameAs":["https:\/\/gersonguelmann.com.br\/blog\/"]}]}},"views":8,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/08\/HojePR-25.jpg?fit=600%2C400&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p96e7O-6Ow","jetpack-related-posts":[{"id":23062,"url":"https:\/\/gersonguelmann.com.br\/blog\/pensando-bem-eu-nao-estou-tao-mal-sexta-do-humor-e-da-cultura-judaica\/","url_meta":{"origin":26196,"position":0},"title":"Pensando Bem, Eu N\u00e3o Estou T\u00e3o Mal&#8230; Sexta do Humor e da Cultura Judaica","author":"Gerson Guelmann zs","date":"17 de mar\u00e7o de 2023","format":false,"excerpt":"Pensando Bem, Eu N\u00e3o Estou T\u00e3o Mal... Rebeca encontrou Sara, uma amiga de juventude que n\u00e3o via h\u00e1 muito tempo, e como ambas j\u00e1 estavam com certa idade, a conversa derivou para os achaques da velhice. Depois que Sara contou sobre seus problemas, chegou a vez de Rebeca fazer seu\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/03\/VELHA-scaled-1.jpg?fit=750%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/03\/VELHA-scaled-1.jpg?fit=750%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/03\/VELHA-scaled-1.jpg?fit=750%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/03\/VELHA-scaled-1.jpg?fit=750%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26467,"url":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-desculpe-numero-errado\/","url_meta":{"origin":26196,"position":1},"title":"Sexta do Humor e da Cultura Judaica &#8211; Desculpe, N\u00famero Errado&#8230;","author":"Gerson Guelmann zs","date":"5 de dezembro de 2025","format":false,"excerpt":"Desculpe, N\u00famero Errado\u2026 Sarah estava tendo um dia terr\u00edvel e ligou para a m\u00e3e: - M\u00e3e, socorro! As crian\u00e7as est\u00e3o insuport\u00e1veis, resfriadas, chorando e implicando com tudo o tempo todo. A casa est\u00e1 uma bagun\u00e7a, a diarista n\u00e3o veio, os Cohens v\u00eam jantar aqui e, para piorar, eles s\u00e3o cheios\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/12\/HojePR-3.png?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/12\/HojePR-3.png?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/12\/HojePR-3.png?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/12\/HojePR-3.png?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/12\/HojePR-3.png?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":23389,"url":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-mao-tse-tung-a-china-e-o-problema-judaico\/","url_meta":{"origin":26196,"position":2},"title":"Sexta do Humor e da Cultura Judaica \u2013 Mao Ts\u00e9-Tung, a China e o Problema Judaico","author":"Gerson Guelmann zs","date":"26 de abril de 2024","format":false,"excerpt":"Mao Ts\u00e9-Tung, a China e o Problema Judaico Conta-se que Yasser Arafat, da OLP, fez uma visita oficial \u00e0 China,\u00a0no in\u00edcio da d\u00e9cada de 1970. O l\u00edder chin\u00eas era Mao Ts\u00e9-Tung, que apesar de aliado do visitante, n\u00e3o demonstrava estar atualizado com a geopol\u00edtica da regi\u00e3o. A certa altura da\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2024\/04\/HojePR-6.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2024\/04\/HojePR-6.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2024\/04\/HojePR-6.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2024\/04\/HojePR-6.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2024\/04\/HojePR-6.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":23101,"url":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-o-jantar-do-rabino-cohen-e-do-padre-kelly\/","url_meta":{"origin":26196,"position":3},"title":"Sexta do Humor e da Cultura Judaica \u2013 O Jantar do Rabino Cohen e do Padre Kelly","author":"Gerson Guelmann zs","date":"5 de maio de 2023","format":false,"excerpt":"O Jantar do Rabino Cohen e do Padre Kelly O Rabino Cohen e o Padre Kelly, muito amigos, foram juntos a um leil\u00e3o beneficente da Comunidade onde trabalhavam. Ap\u00f3s o t\u00e9rmino foi servido um jantar e os religiosos sentaram-se lado a lado. Logo no in\u00edcio foi servida uma entrada e\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/05\/HojePR-1.jpg?fit=960%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/05\/HojePR-1.jpg?fit=960%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/05\/HojePR-1.jpg?fit=960%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/05\/HojePR-1.jpg?fit=960%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26448,"url":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-o-rabino-e-a-vaca\/","url_meta":{"origin":26196,"position":4},"title":"Sexta do Humor e da Cultura Judaica &#8211; O Rabino e a Vaca","author":"Gerson Guelmann zs","date":"21 de novembro de 2025","format":false,"excerpt":"O Rabino e a Vaca A comunidade judaica de uma aldeia polonesa tinha apenas uma vaca para atender todas as fam\u00edlias. Com o tempo, o animal foi envelhecendo e a produ\u00e7\u00e3o de leite foi diminuindo at\u00e9 secar. Os moradores decidiram comprar um novo animal e, depois de pesquisar, encontraram uma\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/11\/HojePR-11.jpg?fit=600%2C398&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/11\/HojePR-11.jpg?fit=600%2C398&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/11\/HojePR-11.jpg?fit=600%2C398&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":23223,"url":"https:\/\/gersonguelmann.com.br\/blog\/sexta-do-humor-e-da-cultura-judaica-o-desespero-de-ana-e-elias\/","url_meta":{"origin":26196,"position":5},"title":"Sexta do Humor e da Cultura Judaica &#8211; O Desespero de Ana e Elias","author":"Gerson Guelmann zs","date":"18 de agosto de 2023","format":false,"excerpt":"O Desespero de Ana e Elias Ana e Elias estavam desesperados. David, seu filho de 3 anos, ainda n\u00e3o tinha aprendido a falar. Nem mesmo uma \u00fanica palavra havia sa\u00eddo dos l\u00e1bios do menino.\u00a0 \u00a0 Em uma sexta-feira, durante o jantar de Shabbat, David provou o caldo de galinha com\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/08\/HojePR-5-scaled.jpg?fit=800%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/08\/HojePR-5-scaled.jpg?fit=800%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/08\/HojePR-5-scaled.jpg?fit=800%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/08\/HojePR-5-scaled.jpg?fit=800%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts\/26196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/comments?post=26196"}],"version-history":[{"count":0,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts\/26196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/media\/26239"}],"wp:attachment":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/media?parent=26196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/categories?post=26196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/tags?post=26196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}