    {"id":26585,"date":"2026-02-04T17:05:58","date_gmt":"2026-02-04T20:05:58","guid":{"rendered":"https:\/\/gersonguelmann.com.br\/blog\/?p=26585"},"modified":"2026-02-05T11:03:46","modified_gmt":"2026-02-05T14:03:46","slug":"tres-na-quarta-de-humor-judaico-75","status":"publish","type":"post","link":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/","title":{"rendered":"Tr\u00eas na Quarta de Humor Judaico"},"content":{"rendered":"<p data-start=\"1797\" data-end=\"1816\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong data-start=\"1801\" data-end=\"1816\">Jogo R\u00e1pido<br \/>\n<\/strong><\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Enquanto assistiam \u00e0 TV, Aron disse para sua esposa, Rose:<\/span><\/p>\n<p data-start=\"1878\" data-end=\"1987\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Voc\u00ea j\u00e1 notou, querida, que o brilho, a excita\u00e7\u00e3o e at\u00e9 o sexo parecem ter desaparecido do nosso casamento?<\/span><\/p>\n<p data-start=\"1989\" data-end=\"2074\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Espere um pouco, respondeu ela. \u201cVamos falar disso no pr\u00f3ximo intervalo comercial.<\/span><\/p>\n<p data-start=\"2081\" data-end=\"2105\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong data-start=\"2085\" data-end=\"2105\">Um Santo Rem\u00e9dio<br \/>\n<\/strong><\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Pergunta: O que Sara faz quando acorda com dor de cabe\u00e7a?<\/span><\/p>\n<p data-start=\"2168\" data-end=\"2215\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Resposta: Manda \u201ca dor de cabe\u00e7a\u201d ir trabalhar.<\/span><\/p>\n<p data-start=\"1383\" data-end=\"1400\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\"><strong data-start=\"1387\" data-end=\"1400\">No M\u00e9dico<br \/>\n<\/strong><\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Na primeira consulta:<br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">M\u00e9dico: O senhor viver\u00e1 at\u00e9 os 80.<\/span><br data-start=\"1461\" data-end=\"1464\" \/><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Paciente: Doutor, eu j\u00e1 estou com quase 80.<\/span><br data-start=\"1509\" data-end=\"1512\" \/><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">M\u00e9dico: Viu s\u00f3? \u00c9 disso que eu estou falando!<\/span><\/p>\n<p data-start=\"1561\" data-end=\"1608\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">O m\u00e9dico ouvindo o paciente com o estetosc\u00f3pio:<br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Paciente: O que eu tenho, doutor?<\/span><br data-start=\"1645\" data-end=\"1648\" \/><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">M\u00e9dico: \u00c9 isso que me intriga!<\/span><\/p>\n<p data-start=\"1682\" data-end=\"1706\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">O paciente se queixando:<br \/>\n<\/span><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Paciente: Eu escuto uma campainha tocando no meu ouvido.<\/span><br data-start=\"1766\" data-end=\"1769\" \/><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">M\u00e9dico: N\u00e3o atenda.<\/span><\/p>\n<p style=\"text-align: center;\" data-start=\"1708\" data-end=\"1790\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"attachment-266x266 size-266x266\" src=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?resize=266%2C266&#038;ssl=1\" sizes=\"(max-width: 266px) 100vw, 266px\" srcset=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?resize=70%2C70&amp;ssl=1 70w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?resize=127%2C127&amp;ssl=1 127w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?resize=476%2C476&amp;ssl=1 476w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?resize=125%2C125&amp;ssl=1 125w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?w=600&amp;ssl=1 600w\" alt=\"\" width=\"266\" height=\"266\" \/><br \/>\n<span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 14pt; color: #0000ff;\"><em><strong>Imagem gerada por I.A.<\/strong><\/em><\/span><\/p>\n<p data-start=\"1708\" data-end=\"1790\">\n","protected":false},"excerpt":{"rendered":"<p>Jogo R\u00e1pido Enquanto assistiam \u00e0 TV, Aron disse para sua esposa, Rose: Voc\u00ea j\u00e1 notou, querida, que o brilho, a excita\u00e7\u00e3o e at\u00e9 o sexo parecem ter desaparecido do nosso casamento? Espere um pouco, respondeu ela. \u201cVamos falar disso no pr\u00f3ximo intervalo comercial. Um Santo Rem\u00e9dio Pergunta: O que Sara faz quando acorda com dor [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":26587,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-26585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tr\u00eas na Quarta de Humor Judaico | Blog do Guelmann<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tr\u00eas na Quarta de Humor Judaico | Blog do Guelmann\" \/>\n<meta property=\"og:description\" content=\"Jogo R\u00e1pido Enquanto assistiam \u00e0 TV, Aron disse para sua esposa, Rose: Voc\u00ea j\u00e1 notou, querida, que o brilho, a excita\u00e7\u00e3o e at\u00e9 o sexo parecem ter desaparecido do nosso casamento? Espere um pouco, respondeu ela. \u201cVamos falar disso no pr\u00f3ximo intervalo comercial. Um Santo Rem\u00e9dio Pergunta: O que Sara faz quando acorda com dor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Guelmann\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-04T20:05:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T14:03:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gerson Guelmann zs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gerson Guelmann zs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-75\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-75\\\/\"},\"author\":{\"name\":\"Gerson Guelmann zs\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\"},\"headline\":\"Tr\u00eas na Quarta de Humor Judaico\",\"datePublished\":\"2026-02-04T20:05:58+00:00\",\"dateModified\":\"2026-02-05T14:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-75\\\/\"},\"wordCount\":151,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-75\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/HojePR-1.png?fit=600%2C600&ssl=1\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-75\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-75\\\/\",\"url\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-75\\\/\",\"name\":\"Tr\u00eas na Quarta de Humor Judaico | Blog do Guelmann\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-75\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-75\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/HojePR-1.png?fit=600%2C600&ssl=1\",\"datePublished\":\"2026-02-04T20:05:58+00:00\",\"dateModified\":\"2026-02-05T14:03:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-75\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/tres-na-quarta-de-humor-judaico-75\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/HojePR-1.png?fit=600%2C600&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/HojePR-1.png?fit=600%2C600&ssl=1\",\"width\":600,\"height\":600},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/\",\"name\":\"Blog do Guelmann\",\"description\":\"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\",\"name\":\"Gerson Guelmann zs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"caption\":\"Gerson Guelmann zs\"},\"description\":\"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.\",\"sameAs\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tr\u00eas na Quarta de Humor Judaico | Blog do Guelmann","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/","og_locale":"pt_BR","og_type":"article","og_title":"Tr\u00eas na Quarta de Humor Judaico | Blog do Guelmann","og_description":"Jogo R\u00e1pido Enquanto assistiam \u00e0 TV, Aron disse para sua esposa, Rose: Voc\u00ea j\u00e1 notou, querida, que o brilho, a excita\u00e7\u00e3o e at\u00e9 o sexo parecem ter desaparecido do nosso casamento? Espere um pouco, respondeu ela. \u201cVamos falar disso no pr\u00f3ximo intervalo comercial. Um Santo Rem\u00e9dio Pergunta: O que Sara faz quando acorda com dor [&hellip;]","og_url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/","og_site_name":"Blog do Guelmann","article_published_time":"2026-02-04T20:05:58+00:00","article_modified_time":"2026-02-05T14:03:46+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png","type":"image\/png"}],"author":"Gerson Guelmann zs","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gerson Guelmann zs","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/#article","isPartOf":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/"},"author":{"name":"Gerson Guelmann zs","@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e"},"headline":"Tr\u00eas na Quarta de Humor Judaico","datePublished":"2026-02-04T20:05:58+00:00","dateModified":"2026-02-05T14:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/"},"wordCount":151,"commentCount":0,"image":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?fit=600%2C600&ssl=1","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/","url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/","name":"Tr\u00eas na Quarta de Humor Judaico | Blog do Guelmann","isPartOf":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/#primaryimage"},"image":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?fit=600%2C600&ssl=1","datePublished":"2026-02-04T20:05:58+00:00","dateModified":"2026-02-05T14:03:46+00:00","author":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-75\/#primaryimage","url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?fit=600%2C600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?fit=600%2C600&ssl=1","width":600,"height":600},{"@type":"WebSite","@id":"https:\/\/gersonguelmann.com.br\/blog\/#website","url":"https:\/\/gersonguelmann.com.br\/blog\/","name":"Blog do Guelmann","description":"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gersonguelmann.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e","name":"Gerson Guelmann zs","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","caption":"Gerson Guelmann zs"},"description":"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.","sameAs":["https:\/\/gersonguelmann.com.br\/blog\/"]}]}},"views":10,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/02\/HojePR-1.png?fit=600%2C600&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p96e7O-6UN","jetpack-related-posts":[{"id":19870,"url":"https:\/\/gersonguelmann.com.br\/blog\/pilulas-de-humor-judaico-27\/","url_meta":{"origin":26585,"position":0},"title":"P\u00edlulas de Humor Judaico (27)","author":"Gerson Guelmann zs","date":"28 de julho de 2021","format":false,"excerpt":"Jac\u00f3 Comprando Pela Internet Jac\u00f3 estava precisando de um novo motor para seu barco de pesca e ap\u00f3s encontrar o que lhe agradou, mandou uma carta para o vendedor: - \"Por favor, me mande o motor que est\u00e1 na p\u00e1gina 438 do cat\u00e1logo e, se for bom, depois eu mando\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2020\/02\/Refinaria.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2020\/02\/Refinaria.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2020\/02\/Refinaria.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2020\/02\/Refinaria.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2020\/02\/Refinaria.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":26364,"url":"https:\/\/gersonguelmann.com.br\/blog\/tres-na-quarta-de-humor-judaico-56\/","url_meta":{"origin":26585,"position":1},"title":"Tr\u00eas na Quarta de Humor Judaico","author":"Gerson Guelmann zs","date":"1 de outubro de 2025","format":false,"excerpt":"No Vel\u00f3rio, as \u00daltimas Palavras Um Padre, um Pastor e um Rabino falavam sobre aposentadoria, a finitude da vida, a morte, essas coisas. Em determinado momento a conversa passou a ser sobre como gostariam de ser lembrados e, especialmente, o que desejavam que seus fieis dissessem quando os vissem no\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/10\/HojePR.jpg?fit=600%2C405&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/10\/HojePR.jpg?fit=600%2C405&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/10\/HojePR.jpg?fit=600%2C405&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":15406,"url":"https:\/\/gersonguelmann.com.br\/blog\/o-avo-judeu-os-tres-netos-e-o-sapo\/","url_meta":{"origin":26585,"position":2},"title":"O Av\u00f4 Judeu, os Tr\u00eas Netos e o Sapo","author":"Gerson Guelmann zs","date":"22 de fevereiro de 2021","format":false,"excerpt":"David, Henry e Alan, tr\u00eas irm\u00e3os, entraram em f\u00e9rias, e os pais os mandaram passar algum tempo com os av\u00f3s. Um dia, David, o menino mais velho, foi at\u00e9 o av\u00f4 e perguntou: - \"Voc\u00ea pode fazer um som como um sapo, Zeide?\" (*)\u00a0 O av\u00f4, de mau humor, respondeu:\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/12\/Frog.jpg?fit=960%2C558&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/12\/Frog.jpg?fit=960%2C558&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/12\/Frog.jpg?fit=960%2C558&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/12\/Frog.jpg?fit=960%2C558&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":762,"url":"https:\/\/gersonguelmann.com.br\/blog\/metodo-judaico-para-espremer-limao\/","url_meta":{"origin":26585,"position":3},"title":"M\u00e9todo Judaico Para Espremer Lim\u00e3o","author":"Gerson Guelmann zs","date":"30 de novembro de 2020","format":false,"excerpt":"Numa cidadezinha americana o dono de um bar estava t\u00e3o seguro de que seu Barman era o homem mais forte das redondezas, que decidiu\u00a0 instituir um desafio: - pedia para o funcion\u00e1rio apertar um lim\u00e3o, cujo suco recolhia num copo. Em seguida dizia que se algu\u00e9m conseguisse espremer mais uma\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/08\/LIMAO.jpg?fit=580%2C406&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/08\/LIMAO.jpg?fit=580%2C406&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/08\/LIMAO.jpg?fit=580%2C406&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":23090,"url":"https:\/\/gersonguelmann.com.br\/blog\/o-diretor-do-banco-e-o-engraxate\/","url_meta":{"origin":26585,"position":4},"title":"O Diretor do Banco e o Engraxate","author":"Gerson Guelmann zs","date":"26 de abril de 2023","format":false,"excerpt":"Todas as manh\u00e3s o CEO de um grande banco em Manhattan ia at\u00e9 a esquina onde um Engraxate atendia a clientela. O ritual era sempre o mesmo: ele sentava na cadeira, lia o Wall Street Journal e o homem fazia o seu trabalho, deixando os sapatos com uma apar\u00eancia brilhante.\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/04\/HojePR-5-scaled.jpg?fit=1200%2C950&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/04\/HojePR-5-scaled.jpg?fit=1200%2C950&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/04\/HojePR-5-scaled.jpg?fit=1200%2C950&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/04\/HojePR-5-scaled.jpg?fit=1200%2C950&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2023\/04\/HojePR-5-scaled.jpg?fit=1200%2C950&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5712,"url":"https:\/\/gersonguelmann.com.br\/blog\/um-video-um-caminho-uma-esperanca\/","url_meta":{"origin":26585,"position":5},"title":"Um V\u00eddeo, Um Caminho, Uma Esperan\u00e7a","author":"Gerson Guelmann zs","date":"13 de janeiro de 2021","format":false,"excerpt":"O v\u00eddeo que voc\u00ea ver\u00e1 a seguir \u00e9 isso tudo o que coloquei no t\u00edtulo e mais um pouco. Foi rodado em Porto Alegre em abril de 2014 para contar a hist\u00f3ria do pequeno Valentim, o Tim Tim, que tinha apenas um ano e cinco meses. O texto, a narra\u00e7\u00e3o\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2021\/01\/AnyConv.com__HOPE-199x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts\/26585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/comments?post=26585"}],"version-history":[{"count":0,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts\/26585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/media\/26587"}],"wp:attachment":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/media?parent=26585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/categories?post=26585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/tags?post=26585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}