    {"id":5583,"date":"2025-07-07T22:00:47","date_gmt":"2025-07-08T01:00:47","guid":{"rendered":"https:\/\/gersonguelmann.com.br\/blog\/?p=5583"},"modified":"2025-07-17T09:07:49","modified_gmt":"2025-07-17T12:07:49","slug":"morreu-o-monge-que-era-judeu","status":"publish","type":"post","link":"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/","title":{"rendered":"Morreu o Monge Que Era Judeu"},"content":{"rendered":"<p data-start=\"516\" data-end=\"784\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Desde que iniciei meu blog, no final de 2016, costumo garimpar material nas fontes dispon\u00edveis na internet. Essa pr\u00e1tica me levou a aprimorar o cruzamento de informa\u00e7\u00f5es \u2014 n\u00e3o apenas para conferir a veracidade delas, mas tamb\u00e9m para me aprofundar nos temas que abordo.<\/span><\/p>\n<p data-start=\"786\" data-end=\"1108\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Sou remanescente de uma gera\u00e7\u00e3o que pesquisava nas enciclop\u00e9dias Barsa, Caldas-Aulete, Britannica, Mirador\u2026 at\u00e9 que o Google se tornou meu aliado. E agora, com o compromisso de publicar tr\u00eas colunas semanais no <em data-start=\"997\" data-end=\"1005\">HojePR<\/em>, encontrei na chamada \u201cI.A.\u201d uma superenciclop\u00e9dia \u00e0 altura \u2014 fascinante e surpreendentemente precisa.<\/span><\/p>\n<p data-start=\"1110\" data-end=\"1352\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Foi em uma dessas buscas que anos atr\u00e1s me deparei com a hist\u00f3ria de Dom Bernardo Bonowitz, um monge trapista norte-americano, nascido em 1949 em Nova York, primog\u00eanito de uma fam\u00edlia judia de origem bielo-russa e polonesa que imigrou para o Brasil e se estabeleceu no Paran\u00e1. E nos idos de 2017 escrevi sobre ele, destacando o fato de um judeu convertido ter assumido cargo de destaque na estrutura da igreja cat\u00f3lica.<\/span><\/p>\n<p data-start=\"1354\" data-end=\"1656\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Ainda adolescente, ele manifestou o desejo de converter-se ao catolicismo. Em 1968, aos 19 anos, foi batizado, j\u00e1 como estudante de L\u00ednguas Cl\u00e1ssicas na Universidade Columbia. Iniciou sua vida religiosa com os Jesu\u00edtas em 1973, e aos 33 anos ingressou no Mosteiro Trapista de Spencer, em Massachusetts.<\/span><\/p>\n<p data-start=\"1658\" data-end=\"2002\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Chegou no Brasil em 1996, com 47 anos, como prior eleito da comunidade de Nossa Senhora do Novo Mundo, em Campo do Tenente \u2014 a apenas 100 quil\u00f4metros de Curitiba. Quando o local foi elevado a Abadia, em 2008, Dom Bernardo tornou-se o primeiro Abade do Mosteiro Trapista Nossa Senhora do Novo Mundo \u2014 o \u00fanico da ordem, masculino, em todo o Brasil.<\/span><\/p>\n<p data-start=\"2004\" data-end=\"2340\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Lembrando da minha postagem, voltei a pesquisar sobre Dom Bernardo e tomei conhecimento do seu falecimento em 19\/01\/2025. Ele conduziu a comunidade por muitos anos com sabedoria e serenidade, at\u00e9 que, j\u00e1 com a sa\u00fade debilitada e ap\u00f3s mais de duas d\u00e9cadas no Brasil, retornou aos Estados Unidos para tratamento de uma doen\u00e7a degenerativa que o fez abandonar o cargo e a vida mon\u00e1stica. Sua partida, agora, n\u00e3o foi exatamente uma surpresa para os que o acompanhavam, mas ainda assim comove \u2014 pelo homem que foi, pela hist\u00f3ria que construiu e pelo sil\u00eancio que deixa.<\/span><\/p>\n<p data-start=\"2342\" data-end=\"2830\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Ganhou destaque na imprensa \u2014 inclusive com uma entrevista ao Programa do J\u00f4 \u2014 n\u00e3o apenas por sua posi\u00e7\u00e3o na hierarquia trapista, mas tamb\u00e9m por sua origem incomum: um monge que havia sido criado no seio do Juda\u00edsmo. Na entrevista, Dom Bernardo comentou que os trapistas rezam oito vezes por dia. Falam apenas o necess\u00e1rio durante o trabalho, comunicando-se por sinais, e vivem sob regras rigorosas: podem visitar a fam\u00edlia apenas a cada cinco anos e receb\u00ea-la por cinco dias a cada dois.<\/span><\/p>\n<p data-start=\"2924\" data-end=\"3178\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">A escolha de f\u00e9 de Dom Bernardo foi pessoal \u2014 como toda f\u00e9 deve ser. Assim como acolhemos crist\u00e3os sinceros que se convertem ao Juda\u00edsmo, devemos saber respeitar \u2014 sem reservas \u2014 aqueles que, em busca de sentido e transcend\u00eancia, trilham o caminho inverso.<\/span><\/p>\n<p data-start=\"3180\" data-end=\"3354\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">F\u00e9 n\u00e3o se imp\u00f5e nem se explica. F\u00e9 \u00e9 sil\u00eancio, \u00e9 busca, \u00e9 entrega. Dom Bernardo parece ter encontrado aquilo que procurava. E por isso merece n\u00e3o a cr\u00edtica, mas a rever\u00eancia.<\/span><\/p>\n<p data-start=\"3180\" data-end=\"3354\"><span style=\"color: #000000; font-family: tahoma, arial, helvetica, sans-serif; font-size: 18pt;\">Para assistir a entrevista de D. Bernardo ao J\u00f4 Soares, <a href=\"https:\/\/globoplay.globo.com\/v\/1497517\/\"><span style=\"color: #0000ff;\"><em><strong>clique aqui<\/strong><\/em><\/span><\/a>.<\/span><\/p>\n<p style=\"text-align: center;\" data-start=\"3180\" data-end=\"3354\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"26148\" data-permalink=\"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/reduzir-7\/\" data-orig-file=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-6.jpg?fit=600%2C957&amp;ssl=1\" data-orig-size=\"600,957\" data-comments-opened=\"1\" data-image-title=\"REDUZIR\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-6.jpg?fit=600%2C957&amp;ssl=1\" class=\"alignnone size-full wp-image-26148\" src=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-6.jpg?resize=600%2C957&#038;ssl=1\" alt=\"\" width=\"600\" height=\"957\" srcset=\"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-6.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-6.jpg?resize=188%2C300&amp;ssl=1 188w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: center;\" data-start=\"3180\" data-end=\"3354\"><span style=\"color: #0000ff;\"><strong><span style=\"font-size: 14pt;\"><em><span style=\"font-family: 'andale mono', monospace;\">Dom Bernardo Bonowitz<\/span><\/em><\/span><\/strong><\/span><br \/>\n<span style=\"color: #0000ff;\"><strong><span style=\"font-size: 14pt;\"><em><span style=\"font-family: 'andale mono', monospace;\">Foto Abadia Trapista Nossa Senhora do Novo Mundo<\/span><\/em><\/span><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">\n","protected":false},"excerpt":{"rendered":"<p>Desde que iniciei meu blog, no final de 2016, costumo garimpar material nas fontes dispon\u00edveis na internet. Essa pr\u00e1tica me levou a aprimorar o cruzamento de informa\u00e7\u00f5es \u2014 n\u00e3o apenas para conferir a veracidade delas, mas tamb\u00e9m para me aprofundar nos temas que abordo. Sou remanescente de uma gera\u00e7\u00e3o que pesquisava nas enciclop\u00e9dias Barsa, Caldas-Aulete, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":26147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-5583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Morreu o Monge Que Era Judeu | Blog do Guelmann<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Morreu o Monge Que Era Judeu | Blog do Guelmann\" \/>\n<meta property=\"og:description\" content=\"Desde que iniciei meu blog, no final de 2016, costumo garimpar material nas fontes dispon\u00edveis na internet. Essa pr\u00e1tica me levou a aprimorar o cruzamento de informa\u00e7\u00f5es \u2014 n\u00e3o apenas para conferir a veracidade delas, mas tamb\u00e9m para me aprofundar nos temas que abordo. Sou remanescente de uma gera\u00e7\u00e3o que pesquisava nas enciclop\u00e9dias Barsa, Caldas-Aulete, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Guelmann\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-08T01:00:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-17T12:07:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"957\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gerson Guelmann zs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gerson Guelmann zs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/morreu-o-monge-que-era-judeu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/morreu-o-monge-que-era-judeu\\\/\"},\"author\":{\"name\":\"Gerson Guelmann zs\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\"},\"headline\":\"Morreu o Monge Que Era Judeu\",\"datePublished\":\"2025-07-08T01:00:47+00:00\",\"dateModified\":\"2025-07-17T12:07:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/morreu-o-monge-que-era-judeu\\\/\"},\"wordCount\":574,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/morreu-o-monge-que-era-judeu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/REDUZIR-5.jpg?fit=600%2C957&ssl=1\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/morreu-o-monge-que-era-judeu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/morreu-o-monge-que-era-judeu\\\/\",\"url\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/morreu-o-monge-que-era-judeu\\\/\",\"name\":\"Morreu o Monge Que Era Judeu | Blog do Guelmann\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/morreu-o-monge-que-era-judeu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/morreu-o-monge-que-era-judeu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/REDUZIR-5.jpg?fit=600%2C957&ssl=1\",\"datePublished\":\"2025-07-08T01:00:47+00:00\",\"dateModified\":\"2025-07-17T12:07:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/morreu-o-monge-que-era-judeu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/morreu-o-monge-que-era-judeu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/REDUZIR-5.jpg?fit=600%2C957&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/REDUZIR-5.jpg?fit=600%2C957&ssl=1\",\"width\":600,\"height\":957},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/\",\"name\":\"Blog do Guelmann\",\"description\":\"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/87e70e2a786888082f941a482c90569e\",\"name\":\"Gerson Guelmann zs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/gersonguelmann.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/EU-IA.jpg?fit=88%2C96&ssl=1\",\"caption\":\"Gerson Guelmann zs\"},\"description\":\"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.\",\"sameAs\":[\"https:\\\/\\\/gersonguelmann.com.br\\\/blog\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Morreu o Monge Que Era Judeu | Blog do Guelmann","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/","og_locale":"pt_BR","og_type":"article","og_title":"Morreu o Monge Que Era Judeu | Blog do Guelmann","og_description":"Desde que iniciei meu blog, no final de 2016, costumo garimpar material nas fontes dispon\u00edveis na internet. Essa pr\u00e1tica me levou a aprimorar o cruzamento de informa\u00e7\u00f5es \u2014 n\u00e3o apenas para conferir a veracidade delas, mas tamb\u00e9m para me aprofundar nos temas que abordo. Sou remanescente de uma gera\u00e7\u00e3o que pesquisava nas enciclop\u00e9dias Barsa, Caldas-Aulete, [&hellip;]","og_url":"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/","og_site_name":"Blog do Guelmann","article_published_time":"2025-07-08T01:00:47+00:00","article_modified_time":"2025-07-17T12:07:49+00:00","og_image":[{"width":600,"height":957,"url":"https:\/\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-5.jpg","type":"image\/jpeg"}],"author":"Gerson Guelmann zs","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gerson Guelmann zs","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/#article","isPartOf":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/"},"author":{"name":"Gerson Guelmann zs","@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e"},"headline":"Morreu o Monge Que Era Judeu","datePublished":"2025-07-08T01:00:47+00:00","dateModified":"2025-07-17T12:07:49+00:00","mainEntityOfPage":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/"},"wordCount":574,"commentCount":2,"image":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-5.jpg?fit=600%2C957&ssl=1","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/","url":"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/","name":"Morreu o Monge Que Era Judeu | Blog do Guelmann","isPartOf":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/#primaryimage"},"image":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-5.jpg?fit=600%2C957&ssl=1","datePublished":"2025-07-08T01:00:47+00:00","dateModified":"2025-07-17T12:07:49+00:00","author":{"@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gersonguelmann.com.br\/blog\/morreu-o-monge-que-era-judeu\/#primaryimage","url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-5.jpg?fit=600%2C957&ssl=1","contentUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-5.jpg?fit=600%2C957&ssl=1","width":600,"height":957},{"@type":"WebSite","@id":"https:\/\/gersonguelmann.com.br\/blog\/#website","url":"https:\/\/gersonguelmann.com.br\/blog\/","name":"Blog do Guelmann","description":"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gersonguelmann.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/gersonguelmann.com.br\/blog\/#\/schema\/person\/87e70e2a786888082f941a482c90569e","name":"Gerson Guelmann zs","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2026\/05\/EU-IA.jpg?fit=88%2C96&ssl=1","caption":"Gerson Guelmann zs"},"description":"Pitadas da sabedoria e do humor judaicos, assuntos do momento e um pouco das hist\u00f3rias que vivi e testemunhei.","sameAs":["https:\/\/gersonguelmann.com.br\/blog\/"]}]}},"views":601,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2025\/07\/REDUZIR-5.jpg?fit=600%2C957&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p96e7O-1s3","jetpack-related-posts":[{"id":143,"url":"https:\/\/gersonguelmann.com.br\/blog\/meu-pai-e-a-heranca-do-vovo-salomao\/","url_meta":{"origin":5583,"position":0},"title":"Meu Pai e a Heran\u00e7a do Vov\u00f4 Salom\u00e3o","author":"Gerson Guelmann zs","date":"11 de junho de 2017","format":false,"excerpt":"H\u00e1 poucos dias contei a hist\u00f3ria de um Colaborador que come\u00e7ou a trabalhar com meu av\u00f4 Salom\u00e3o antes de o meu pai nascer. Acredito que existiam outros casos, e de cabe\u00e7a lembro de pelo menos mais um. A ind\u00fastria tinha uma serraria na localidade de Banhados, em Guarapuava, e l\u00e1\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/4.bp.blogspot.com\/-DfF04NoqMGA\/WT21ZojOmNI\/AAAAAAAAS6Q\/AB2DC98fbIgm_dJtOdWHekZ5TfpFeswJQCLcB\/s320\/images%25287%2529.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":15324,"url":"https:\/\/gersonguelmann.com.br\/blog\/o-prontuario-medico-de-um-pai-mais-uma-do-carpinejar\/","url_meta":{"origin":5583,"position":1},"title":"O Prontu\u00e1rio M\u00e9dico de Um Pai (Mais Uma do Carpinejar)","author":"Gerson Guelmann zs","date":"29 de novembro de 2018","format":false,"excerpt":"Sou um fervoroso admirador do Fabr\u00edcio Carpinejar, na minha opini\u00e3o dono de um dos mais brilhantes textos do pa\u00eds. Suas cr\u00f4nicas falam ao nosso cora\u00e7\u00e3o, ao tratar de sentimentos que est\u00e3o a\u00ed, bem diante de nossos olhos, faltando apenas que algu\u00e9m que lhes d\u00ea forma. O mais recente exemplo disso\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2018\/11\/son-and-old-father.jpg?fit=500%2C750&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":157,"url":"https:\/\/gersonguelmann.com.br\/blog\/dois-anjos-no-colegio-estadual-do-parana\/","url_meta":{"origin":5583,"position":2},"title":"Dois Anjos no Col\u00e9gio Estadual do Paran\u00e1","author":"Gerson Guelmann zs","date":"23 de setembro de 2024","format":false,"excerpt":"Carlos Thiago Gon\u00e7alves de Ferrante foi um amigo muito, muito especial. O dia de ontem, me lembrou o Bruno, seu querido filho, marcou o 20\u00ba anivers\u00e1rio de sua partida, pouco antes de completar 56.\u00a0 Nos conhecemos muito jovens, em 1963, no CEP - Col\u00e9gio Estadual do Paran\u00e1. Ele era pouco\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2024\/09\/HojePR-8-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2024\/09\/HojePR-8-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2024\/09\/HojePR-8-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2024\/09\/HojePR-8-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2024\/09\/HojePR-8-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4093,"url":"https:\/\/gersonguelmann.com.br\/blog\/e-o-pior-e-que-essa-gente-vota-38\/","url_meta":{"origin":5583,"position":3},"title":"E o Pior \u00e9 Que Essa Gente Vota (38)","author":"Gerson Guelmann zs","date":"6 de novembro de 2017","format":false,"excerpt":"Mais uma do meu colecionador preferido de 'P\u00e9rolas do Enem\" (vamos esperar a nova safra): - \"Ate\u00edsmo \u00e9 uma religi\u00e3o an\u00f4nima praticada escondido. Na \u00e9poca de Nero, os romanos ateus reuniam-se para rezar nas catatumbas crist\u00e3s\". E o coment\u00e1rio dele: - \"E alguns ainda vivem nas \"catatumbas\". \u00a0","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/11\/Catacumbas-1.jpg?fit=1200%2C656&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/11\/Catacumbas-1.jpg?fit=1200%2C656&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/11\/Catacumbas-1.jpg?fit=1200%2C656&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/11\/Catacumbas-1.jpg?fit=1200%2C656&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/11\/Catacumbas-1.jpg?fit=1200%2C656&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":18785,"url":"https:\/\/gersonguelmann.com.br\/blog\/um-bilhete-a-30-mil-pes-e-o-mundo-fica-melhor\/","url_meta":{"origin":5583,"position":4},"title":"Um Bilhete a 30 Mil P\u00e9s \u2014 E o Mundo Fica Melhor","author":"Gerson Guelmann zs","date":"7 de abril de 2025","format":false,"excerpt":"Um gesto simples de uma comiss\u00e1ria de bordo lembra que a gentileza ainda tem lugar, mesmo nas alturas (e que ainda vale a pena acreditar nas pessoas). H\u00e1 gestos que n\u00e3o se apagam com o tempo. Permanecem na mem\u00f3ria como delicadas provas de que ainda h\u00e1 espa\u00e7o para a gentileza\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2019\/10\/Aeromo%C3%A7a.jpg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2019\/10\/Aeromo%C3%A7a.jpg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2019\/10\/Aeromo%C3%A7a.jpg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2019\/10\/Aeromo%C3%A7a.jpg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1156,"url":"https:\/\/gersonguelmann.com.br\/blog\/nao-discuta-com-uma-mulher-teimosa-uma-fabula-moderna\/","url_meta":{"origin":5583,"position":5},"title":"N\u00e3o Discuta Com Uma Mulher Teimosa! (Uma F\u00e1bula Moderna)","author":"Gerson Guelmann zs","date":"1 de dezembro de 2020","format":false,"excerpt":"Uma pobre mulher, camponesa, saiu com seu machado para buscar lenha na beira do rio. Ao tentar cortar o galho de uma \u00e1rvore, o machado escapou de suas m\u00e3os e caiu na \u00e1gua.\u00a0 \u00a0 Ela se p\u00f4s a chorar e, religiosa que era, rezou pedindo que D-us a ajudasse. Ele\u00a0apareceu\u2026","rel":"","context":"Em &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/gersonguelmann.com.br\/blog\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/08\/Machado.jpg?fit=960%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/08\/Machado.jpg?fit=960%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/08\/Machado.jpg?fit=960%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/gersonguelmann.com.br\/blog\/wp-content\/uploads\/2017\/08\/Machado.jpg?fit=960%2C638&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts\/5583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5583"}],"version-history":[{"count":0,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/posts\/5583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/media\/26147"}],"wp:attachment":[{"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gersonguelmann.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}